{"id":10328,"date":"2018-12-01T14:34:32","date_gmt":"2018-12-01T12:34:32","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=10328"},"modified":"2018-12-01T14:34:32","modified_gmt":"2018-12-01T12:34:32","slug":"regen-fuer-alle-2","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/regen-fuer-alle-2\/","title":{"rendered":"Regen f\u00fcr alle"},"content":{"rendered":"<div class=\"intro\">\n<h1 class=\"isFirstInSlot\" style=\"text-align: justify;\">Regen f\u00fcr alle<\/h1>\n<div class=\"docData news\" style=\"text-align: justify;\"><\/div>\n<div class=\"abstract\" style=\"text-align: justify;\">\n<p>Es ist l\u00e4ngst kein Geheimnis mehr, dieses Jahr war bisher insgesamt erheblich zu trocken. Nun aber ziehen mit Westwind endlich wieder Tiefdruckgebiete \u00fcber uns hinweg und es f\u00e4llt \u00fcberall etwas Regen.<\/p>\n<\/div>\n<\/div>\n<div class=\"body-text\" style=\"text-align: justify;\">\n<p>Nach der gro\u00dfen Trockenheit der vergangenen Monate &#8211; wir haben mehrmals im Thema des Tages dar\u00fcber berichtet &#8211; f\u00e4llt nun mit einer l\u00e4nger anhaltenden Weststr\u00f6mung in den kommenden Tagen wiederholt und verbreitet Regen. Der ein oder andere h\u00e4tte vielleicht lieber Schnee im Dezember, aber die Natur braucht Wasser und das am besten in Form von stetigem Regen, der die Erde langsam durchdringen kann und f\u00fcr eine nachhaltige Befeuchtung sorgt. Wasser, das auch die Fl\u00fcsse und Seen wieder ein wenig bef\u00fcllt.<\/p>\n<p>Bei Westwind f\u00e4llt der meiste Regen in den Weststaulagen, also im Schwarzwald, in der Eifel, am Rothaargebirge und im Bayerischen Wald. Auf ihrem Weg nach Osten regnet sich die feuchte Luftmasse etwas ab, sodass im Osten des Landes deutlich weniger Niederschlag ankommt. W\u00e4hrend im Westen in den kommenden 7 Tagen, also bis n\u00e4chste Woche Samstag, 40 bis 60 Liter pro Quadratmeter zusammenkommen k\u00f6nnen, werden im gleichen Zeitraum im Osten Deutschlands nur 20 bis 40 Liter, also nur etwa die H\u00e4lfte des Niederschlags erwartet. In den Staulagen des Westens und S\u00fcdens liegen die Mengen zwischen 70 und 90, \u00f6rtlich deutlich \u00fcber 100 Liter pro Quadratmeter.<\/p>\n<p>Nat\u00fcrlich sind sich die Wettermodelle noch nicht ganz einig, wie viel Niederschlag insgesamt fallen kann, jedoch sind sich alle einig, dass f\u00fcr jeden Winkel des Landes zumindest ein bisschen des dringend ben\u00f6tigten Wassers dabei ist. Im Osten und Nordosten Deutschlands sind je nach Modell Niederschlagsmengen zwischen 15 und 40, lokal auch um 50 Liter pro Quadratmeter m\u00f6glich. In der Westh\u00e4lfte und im S\u00fcden prognostizieren die Modelle Mengen zwischen 40 und 70, in den Staulagen des Schwarzwaldes und des Allg\u00e4us bis zu 180 Liter.<\/p>\n<p>Da die Niederschl\u00e4ge konvektiv durchsetzt, das hei\u00dft schauerartig oder vereinzelt auch gewittrig verst\u00e4rkt sein werden, k\u00f6nnen sich auf kleinerem Raum Abweichungen von 10 bis 15 Liter pro Quadratmeter ergeben. Sowohl die aus den Modellen, als auch aus dem MOS (Model Output Statitics) errechneten Niederschlagssummen (vergleiche Grafik im Thema des Tages: https:\/\/www.dwd.de\/DE\/wetter\/thema_des_tages\/2018\/12\/01.html) k\u00f6nnen diese lokalen Abweichungen nicht wiedergeben. Die Mengen, die sich aus den Produkten ablesen lassen, sind daher nur als Richtmengen \u00fcber eine gr\u00f6\u00dfere Fl\u00e4che zu sehen.<\/p>\n<p>Auch nach dem n\u00e4chsten Samstag deutet nichts auf eine R\u00fcckkehr zu einer l\u00e4nger anhaltenden Trockenperiode hin. Zwar sind zu Beginn der dritten Adventwoche mit Hochdruckeinfluss wieder ein paar Tage trockenes Wetter zu erwarten, eine blockierende Lage ist derzeit aber nicht in Sicht. Im Gegenteil, zum heutigen Zeitpunkt rechnen die Modelle in der zweiten Wochenh\u00e4lfte mit neuen Tiefdruckgebieten. Da es sich dann mit auf n\u00f6rdliche Richtungen drehenden Wind merklich abk\u00fchlen soll, k\u00f6nnten die Niederschl\u00e4ge bis in tiefe Lagen in Schnee \u00fcbergehen.<\/p>\n<p>Dipl.-Met. Jacqueline Kernn<\/p>\n<p>Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 01.12.2018<\/p>\n<p>Copyright (c) Deutscher Wetterdienst<\/p>\n<p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/12\/5AB7C50E-D96E-4AE8-8AA6-273214882219.gif\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10329\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/regen-fuer-alle-2\/5ab7c50e-d96e-4ae8-8aa6-273214882219\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/12\/5AB7C50E-D96E-4AE8-8AA6-273214882219.gif\" data-orig-size=\"800,785\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Regen f\u00fcr alle\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/12\/5AB7C50E-D96E-4AE8-8AA6-273214882219.gif\" class=\"alignnone size-full wp-image-10329\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/12\/5AB7C50E-D96E-4AE8-8AA6-273214882219.gif\" alt=\"Regen f\u00fcr alle \" width=\"800\" height=\"785\" \/><\/a><\/p>\n<\/div>\n<div class=\"image\" style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Regen f\u00fcr alle Es ist l\u00e4ngst kein Geheimnis mehr, dieses Jahr war bisher insgesamt erheblich zu trocken. Nun aber ziehen mit Westwind endlich wieder Tiefdruckgebiete \u00fcber uns hinweg und es f\u00e4llt \u00fcberall etwas Regen. Nach der gro\u00dfen Trockenheit der vergangenen <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/regen-fuer-alle-2\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10329,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[218,25,297],"yst_prominent_words":[5416,5875,5825,10708,1216,5649,4311,3586,5015,10706,2162,2157,5044,3352,2439,2163,2019,5808,1577,4795],"class_list":["post-10328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-herbst","tag-regen","tag-winter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/12\/5AB7C50E-D96E-4AE8-8AA6-273214882219.gif","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-2GA","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/10328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=10328"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/10328\/revisions"}],"predecessor-version":[{"id":10330,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/10328\/revisions\/10330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/10329"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=10328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=10328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=10328"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=10328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}