{"id":10825,"date":"2019-03-10T10:25:49","date_gmt":"2019-03-10T08:25:49","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=10825"},"modified":"2019-03-10T10:25:59","modified_gmt":"2019-03-10T08:25:59","slug":"wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-10-03-2019","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-10-03-2019\/","title":{"rendered":"Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle 10.03.2019"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/h2>\n<div id=\"attachment_10829\" style=\"width: 838px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10829\" data-attachment-id=\"10829\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-10-03-2019\/85cfb7c5-2ff0-4de6-9d73-34633d30eae0\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/03\/85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0.png\" data-orig-size=\"828,302\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/03\/85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0.png\" class=\"wp-image-10829 size-full\" title=\"Wettervorhersage, Brachwitz, Wettin-L\u00f6bej\u00fcn, Halle, Beidersee, brachwitz, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, Gimritz, Gottgau, Halle, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, Rothenburg, saalekreis, Salzm\u00fcnde, Schiepzig, Schlettau, Taupunkt, Temperatur, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/03\/85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0.png\" alt=\"\" width=\"828\" height=\"302\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/03\/85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0.png 828w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/03\/85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0-300x109.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/03\/85CFB7C5-2FF0-4DE6-9D73-34633D30EAE0-768x280.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a><p id=\"caption-attachment-10829\" class=\"wp-caption-text\">www.yr.no (Klicke auf das Bild)<\/p><\/div>\n<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n<p>Im S\u00fcden ab dem <b>Nachmittag<\/b> schwere Sturmb\u00f6en, vor\u00fcbergehend Unwettergefahr infolge orkanartiger B\u00f6en. <b>Nachts<\/b> Schnee bis ins Tiefland.<\/p>\n<p>Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: <b>Heute<\/b> zieht ein Sturmtief \u00fcber die Mitte Deutschlands von West nach Ost. Dabei gelangt erst milde, ab den <b>Nachmittagsstunden<\/b> deutlich k\u00e4ltere Luft in die Region. Auch in den folgenden Tagen \u00fcberqueren Tiefausl\u00e4ufer Sachsen-Anhalt, so dass die wechselhafte Witterung erhalten bleibt.<\/p>\n<p>STURM\/ORKAN: In den s\u00fcdlichen Landesteilen ab dem <b>Nachmittag<\/b> deutliche Zunahme des S\u00fcdwest- bis Westwindes. Dabei schwere Sturmb\u00f6en um 90 km\/h (Bft 10), <b>abends<\/b> und in der ersten <b>Nachth\u00e4lfte<\/b>kurzzeitig auch erh\u00f6hte Wahrscheinlichkeit von orkanartigen B\u00f6en bis 110 km\/h (Bft 11) (UNWETTER). Gegen <b>Mitternacht<\/b> deutliches Nachlassen des Windes.<\/p>\n<p>Auf dem Brocken tags\u00fcber schwere Sturmb\u00f6en um 90 km\/h (Bft 10), <b>nachts<\/b> vor\u00fcbergehend Orkan bis 130 km\/h (Bft 12).<\/p>\n<p>SCHNEE: <b>Abends<\/b> in der Altmark \u00dcbergang der Niederschl\u00e4ge in Schnee. Dabei vor\u00fcbergehend Gl\u00e4tte durch geringen Neuschnee. <b>Nachts<\/b> im Harz absinkende Schneefallgrenze bis auf 300 m und bis zum <b>Montag<\/b> bis 10 cm Neuschnee.<\/p>\n<p>Detaillierter Wetterablauf: <b>Heute<\/b> <b>Vormittag<\/b> und im weiteren Tagesverlauf bedeckt und verbreitet Regen, der am <b>Abend<\/b> in der Altmark und im Oberharz in Schnee \u00fcbergeht. In den s\u00fcdlichen Landesteilen am <b>Nachmittag<\/b> und am <b>Abend<\/b> Schauer. H\u00f6chsttemperaturen 6 bis 8, im Harz 1 bis 5 Grad. Schwacher, am <b>Nachmittag<\/b> im S\u00fcden aber deutlich zunehmender S\u00fcdwest- bis Westwind mit schweren Sturmb\u00f6en und \u00f6rtlich orkanartigen B\u00f6en. Unwettergefahr. In der <b>Nacht<\/b> zum <b>Montag<\/b> stark bew\u00f6lkt bis bedeckt und bis ins Tiefland Schneeschauer. Oberhalb 300 m etwas Neuschnee. Temperaturr\u00fcckgang auf 2 bis 0, im Harz auf 1 bis -4 Grad. Starker Westwind mit schweren Sturmb\u00f6en im S\u00fcden, anfangs kurzzeitig orkanartige B\u00f6en.<\/p>\n<p>Am <b>Montag<\/b> Schauerwetter. Teils bis ins Tiefland Schnee und Graupel. Zwischendurch kurze Auflockerungen. H\u00f6chstwerte nur zwischen 4 und 7, im Harz je nach H\u00f6henlage zwischen -1 und 4 Grad. Frischer, vor allem in Schauern\u00e4he st\u00fcrmischer Wind aus West bis Nordwest. In der <b>Nacht<\/b> zum <b>Dienstag<\/b>rasch nachlassende Schaueraktivit\u00e4t, dann zum Teil aufklarend. Temperaturr\u00fcckgang auf 1 bis -2 Grad. Schwacher bis m\u00e4\u00dfiger Nordwestwind.<\/p>\n<p>Am <b>Dienstag<\/b> Wechsel zwischen Sonne und Wolken. Weitgehend niederschlagsfrei. Maximal 5 bis 9, im Harz -1 bis 4 Grad. Schwacher S\u00fcdwestwind. In der <b>Nacht<\/b> zum <b>Mittwoch<\/b> zunehmende Bew\u00f6lkung. Nur vereinzelt etwas Regen. Temperaturr\u00fcckgang auf 5 bis 2 Grad. M\u00e4\u00dfiger Wind aus S\u00fcdwest.<\/p>\n<p>Am <b>Mittwoch<\/b> viele Wolken, aber auch etwas Sonne. Meist trocken. Maximal 6 bis 9, im Harz 2 bis 6 Grad. M\u00e4\u00dfiger S\u00fcdwestwind. In der <b>Nacht<\/b> zum <b>Donnerstag<\/b>stark bew\u00f6lkt und gelegentlich Regen. Temperaturr\u00fcckgang auf 5 bis 3, im Harz bis 0 Grad. M\u00e4\u00dfiger auf Nordwest drehender Wind.<\/p>\n<p>Deutscher Wetterdienst, RWB Leipzig, Thomas Hain<\/p>\n<h3>Mehr Wetter?<\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"idlTM2MhUB\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\">Wettervorhersage<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettervorhersage&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/embed\/#?secret=hNfOT5ZttL#?secret=idlTM2MhUB\" data-secret=\"idlTM2MhUB\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"TAirkBx0pR\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/\">Wetterwarnungen<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wetterwarnungen&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/embed\/#?secret=77pSWdycSA#?secret=TAirkBx0pR\" data-secret=\"TAirkBx0pR\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"WCY86vNkal\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/\">Wettercam<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettercam&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/embed\/#?secret=5LGSUSlmkf#?secret=WCY86vNkal\" data-secret=\"WCY86vNkal\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle Im S\u00fcden ab dem Nachmittag schwere Sturmb\u00f6en, vor\u00fcbergehend Unwettergefahr infolge orkanartiger B\u00f6en. Nachts Schnee bis ins Tiefland. Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Heute zieht ein Sturmtief \u00fcber <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-10-03-2019\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[4859,39,4875,4870,4869,4881,4885,4882,4868,4884,4860,4887,5,4883,4873,4872,44,4878,487,4874,4877,4879,4876,63,462,772,628,95,953,2300,4871,4880,4886,1006,231,708,4,94,38,43,96,113],"yst_prominent_words":[2346,11169,1319,1691,1683,1793,1120,3061,2217,7584,7577,9720,1324,11168,2087,2027,1792,1564,2216,2028],"class_list":["post-10825","post","type-post","status-publish","format-standard","hentry","category-wetterblog","tag-beidersee","tag-brachwitz","tag-deutleben","tag-dobis","tag-doeblitz","tag-domnitz","tag-dornitz","tag-doesel","tag-friedrichschwerz","tag-garsena","tag-gimritz","tag-gottgau","tag-halle","tag-kloschwitz","tag-lettewitz","tag-lettin","tag-loebejuen","tag-merbitz","tag-morl","tag-muecheln","tag-nauendorf","tag-neuragozy","tag-neutz-lettewitz","tag-niederschlag","tag-rothenburg","tag-saalefaehren","tag-saalekiez","tag-saalekreis","tag-saalepiraten","tag-saaleschifffahrt","tag-salzmuende","tag-schiepzig","tag-schlettau","tag-taupunkt","tag-temperatur","tag-vorhersage","tag-wetter","tag-wetterbericht","tag-wettervorhersage","tag-wettin","tag-wettin-loebejuen","tag-wind"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-2OB","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/10825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=10825"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/10825\/revisions"}],"predecessor-version":[{"id":10830,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/10825\/revisions\/10830"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=10825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=10825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=10825"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=10825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}