{"id":11347,"date":"2019-07-27T13:43:10","date_gmt":"2019-07-27T11:43:10","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=11347"},"modified":"2019-07-27T13:43:13","modified_gmt":"2019-07-27T11:43:13","slug":"gewitter-ist-nicht-gleich-gewitter-die-superzelle-ein-rotierendes-monster","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-ist-nicht-gleich-gewitter-die-superzelle-ein-rotierendes-monster\/","title":{"rendered":"Gewitter ist nicht gleich Gewitter &#8211; die Superzelle, ein rotierendes Monster"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gewitter treten in ganz unterschiedlichen Erscheinungsformen auf. Im heutigen Thema des Tages wird die Superzelle vorgestellt, ein rotierendes &#8222;Monster&#8220; mit erheblichem Zerst\u00f6rungspotential.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gewitter k\u00f6nnen gro\u00dfe Sch\u00e4den verursachen und f\u00fcr Menschen im Freien sogar lebensgef\u00e4hrlich werden. Extreme Unwetter im Mittelmeerraum vor ein paar Tagen zeigten dies eindrucksvoll (siehe Thema des Tages vom 11. Juli). Besonders gef\u00e4hrlich ist die sogenannte &#8222;Superzelle&#8220;, eine rotierende und langlebige Gewitterwolke.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Superzellen sind vielen vor allem aus dem mittleren Westen der USA bekannt. J\u00e4hrlich zieht es hunderte Gewitterj\u00e4ger (Stormchaser) in diese Region, sogar aus Deutschland, um die majest\u00e4tisch anmutenden Gewitter zu verfolgen und zu fotografieren. Durch die meteorologischen Voraussetzungen und das flache Terrain k\u00f6nnen sich Superzellen dort ungehindert entwickeln und ihre gr\u00f6\u00dfte St\u00e4rke entfalten. Sie sind durch ihre zerst\u00f6rerischen Tornados bekannt, die dort jedes Jahr \u00fcber das Land ziehen und alles, was ihnen in die Quere kommt, dem Erdboden gleich machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was viele nicht wissen, auch bei uns in Deutschland sind Superzellen gar nicht so selten und kommen j\u00e4hrlich mehrfach vor. Die in diesem Jahr bisher wohl spektakul\u00e4rste Superzelle war das Hagelunwetter, das am 10. Juni im Allg\u00e4u entstand und auf seinem Weg nach Nordosten vor allem im Raum Ammersee und im M\u00fcnchner Norden Hagelbrocken von 4 bis 8 cm Durchmesser produzierte und sich erst im Bayrischen Wald wieder aufl\u00f6ste (siehe Thema des Tages vom 11. Juni). Am 28. Juli 2013 verursachte 8 cm gro\u00dfer Hagel einer Superzelle rund um Reutlingen mit 2,8 Mrd. Euro den bisher gr\u00f6\u00dften Hagelschaden der Geschichte Deutschlands und mehrere Hundert Menschen wurden verletzt. Nur ein paar Tage sp\u00e4ter, am 8. August, fand man ebenfalls bei Reutlingen mit 14 cm den gr\u00f6\u00dften Hagelbrocken Deutschlands. Auch beim M\u00fcnchner Hagelunwetter vom 12. Juli 1984 handelte es sich um eine Superzelle. Damals kamen \u00fcber der Millionenstadt bis zu 9,5 cm gro\u00dfe und 300 g schwere Hagelgeschosse vom Himmel!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine detaillierte Beschreibung der komplexen Luftstr\u00f6mungen in einer Superzelle (Abb. 1) w\u00fcrde an dieser Stelle den Rahmen sprengen, sodass nur die grundlegenden Merkmale erl\u00e4utert werden. Die markanteste Eigenschaft der Superzelle ist ihr rotierender Aufwindschlauch (Updraft). Wie bereits im Thema des Tages vom 6. Juli erkl\u00e4rt wurde, entscheidet vor allem die St\u00e4rke der vertikalen Windscherung (Zunahme der Windgeschwindigkeit und \u00c4nderung der Windrichtung mit der H\u00f6he), welche Gewitterform sich bildet. Superzellen entstehen in einer Region, in der eine hochreichende und starke Windscherung vorherrscht und bodennah Warmluft einflie\u00dft. Bei uns in Deutschland sind diese Voraussetzungen beispielsweise an der Vorderseite eines H\u00f6hentiefs mit Zentrum \u00fcber Westeuropa gegeben. Dabei erreicht uns in tieferen Luftschichten feuchte subtropische Warmluft, also eine sehr energiereiche Luftmasse (hohe CAPE), und der Wind erf\u00e4hrt eine deutliche Rechtsdrehung mit der H\u00f6he. Durch die starke Windzunahme in der unteren Atmosph\u00e4re beginnt die Luft horizontal zu rotieren. Der Updraft (rote Pfeile, Abb. 1+2) kippt nun den rotierenden Wirbel in die Senkrechte und verst\u00e4rkt ihn weiter. Durch die Rechtsdrehung des Winds entsteht so ein gegen den Uhrzeigersinn rotierender Aufwindschlauch mit einem Durchmesser von zwei bis zehn Kilometern, die sogenannte &#8222;Mesozyklone&#8220;. Sie ist der eigentliche Motor der Superzelle. Durch die aufsteigende Luft erzeugt sie am Boden einen Unterdruck (kleinr\u00e4umiges Tief), wodurch best\u00e4ndig Warmluft in die Gewitterwolke gesaugt werden und aufsteigen kann. Man erkennt diesen Vorgang oft an der sogenannten &#8222;Wallcloud&#8220;, einer Absenkung der Wolkenbasis (Abb. 2+4). Die Scherung sorgt zudem daf\u00fcr, dass die ausflie\u00dfende Kaltluft des Downdrafts (hellblaue Pfeile, Abb. 1+3) hinter der in die Superzelle aufsteigenden Warmluft bleibt (B\u00f6enlinie in Abb. 1). Somit kann die Superzelle kontinuierlich mit der energiereichen Warmluft gef\u00fcttert werden. Durch die Langlebigkeit und die massive Power des rotierenden Updrafts k\u00f6nnen die Hagelk\u00f6rner mehrfach angesaugt und in die H\u00f6he katapultiert werden. So k\u00f6nnen sie zu immer gr\u00f6\u00dferen Brocken heranwachsen, bis sie aufgrund ihrer Schwere schlie\u00dflich zu Boden fallen. Vor allem an der B\u00f6enlinie kann es extreme Fallb\u00f6en (Downbursts) geben. Man erkennt sie an der sogenannten &#8222;Shelfcloud&#8220; (Abb. 3+4). Auch durch absinkende Kaltluft aus dem Amboss (dunkelblaue Pfeile, in Abb. 1) kann es am Boden zu Sturmb\u00f6en kommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zwar ist eine isolierte Superzelle streng genommen auch eine Einzelzelle, sie ist aber weitaus m\u00e4chtiger und langlebiger als ihr nicht-rotierendes Pendant. Im unteren Teil hat das Gewitter oft eine Ausdehnung von 20 bis 50 Kilometern, der Cirrusschirm im oberen Bereich der Wolke kann sogar einen Durchmesser von \u00fcber 100 Kilometern besitzen. Superzellen existieren meist \u00fcber mehrere Stunden, im Extremfall sogar sechs bis zw\u00f6lf Stunden. Daher k\u00f6nnen sie \u00fcber hunderte von Kilometern ziehen und selbst ohne Tornados eine Schneise der Verw\u00fcstung hinterlassen, insbesondere durch extremen Hagelschlag. Die Rotation der Superzelle erkl\u00e4rt auch die Bildung von Tornados. Zudem erreichen die Fallb\u00f6en teils Orkanst\u00e4rke und verursachen erhebliche Sch\u00e4den. So majest\u00e4tisch sch\u00f6n sie f\u00fcr den Beobachter aus der Ferne wirken, so gef\u00e4hrlich und angsteinfl\u00f6\u00dfend sind sie also, wenn man von ihnen getroffen wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. rer. nat. Markus \u00dcbel (Meteorologe)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 14.07.2019<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Copyright (c) Deutscher Wetterdienst<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" data-attachment-id=\"11348\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-ist-nicht-gleich-gewitter-die-superzelle-ein-rotierendes-monster\/cc892b56-0426-42fc-ad5e-7408e266d45f\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F.png\" data-orig-size=\"1285,853\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"CC892B56-0426-42FC-AD5E-7408E266D45F\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F-1024x680.png\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F-1024x680.png\" alt=\"\" class=\"wp-image-11348\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F-1024x680.png 1024w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F-300x199.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F-768x510.png 768w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F.png 1285w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Gewitter treten in ganz unterschiedlichen Erscheinungsformen auf. Im heutigen Thema des Tages wird die Superzelle vorgestellt, ein rotierendes &#8222;Monster&#8220; mit erheblichem Zerst\u00f6rungspotential. Gewitter k\u00f6nnen gro\u00dfe Sch\u00e4den verursachen und f\u00fcr Menschen im Freien sogar lebensgef\u00e4hrlich werden. Extreme Unwetter im Mittelmeerraum vor <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-ist-nicht-gleich-gewitter-die-superzelle-ein-rotierendes-monster\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":11348,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[41,11542],"yst_prominent_words":[5706,9242,1939,1216,1411,5371,7642,3267,3057,5352,7456,11539,11538,11537,4213,11535,4806,4522,4219,4040],"class_list":["post-11347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-gewitter","tag-superzelle"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/07\/CC892B56-0426-42FC-AD5E-7408E266D45F.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-2X1","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11347"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11347\/revisions"}],"predecessor-version":[{"id":11349,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11347\/revisions\/11349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/11348"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=11347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=11347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=11347"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=11347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}