{"id":11402,"date":"2019-08-09T05:38:14","date_gmt":"2019-08-09T03:38:14","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=11402"},"modified":"2019-08-09T05:38:25","modified_gmt":"2019-08-09T03:38:25","slug":"wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-09-08-2019","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-09-08-2019\/","title":{"rendered":"Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle 09.08.2019"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/h2>\n<div id=\"attachment_11406\" style=\"width: 838px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11406\" data-attachment-id=\"11406\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-09-08-2019\/faebd255-63b3-4224-bf2a-f62fd5aaf687\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/08\/FAEBD255-63B3-4224-BF2A-F62FD5AAF687.png\" data-orig-size=\"828,302\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"FAEBD255-63B3-4224-BF2A-F62FD5AAF687\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/08\/FAEBD255-63B3-4224-BF2A-F62FD5AAF687.png\" class=\"wp-image-11406 size-full\" title=\"Wettervorhersage, Brachwitz, Wettin-L\u00f6bej\u00fcn, Halle, Beidersee, brachwitz, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, Gimritz, Gottgau, Halle, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, Rothenburg, saalekreis, Salzm\u00fcnde, Schiepzig, Schlettau, Taupunkt, Temperatur, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/08\/FAEBD255-63B3-4224-BF2A-F62FD5AAF687.png\" alt=\"Wettervorhersage, Brachwitz, Wettin-L\u00f6bej\u00fcn, Halle, Beidersee, brachwitz, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, Gimritz, Gottgau, Halle, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, Rothenburg, saalekreis, Salzm\u00fcnde, Schiepzig, Schlettau, Taupunkt, Temperatur, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" width=\"828\" height=\"302\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/08\/FAEBD255-63B3-4224-BF2A-F62FD5AAF687.png 828w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/08\/FAEBD255-63B3-4224-BF2A-F62FD5AAF687-300x109.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2019\/08\/FAEBD255-63B3-4224-BF2A-F62FD5AAF687-768x280.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a><p id=\"caption-attachment-11406\" class=\"wp-caption-text\">www.yr.no (Klicke auf das Bild)<\/p><\/div>\n<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n<p><b>Heute<\/b> erst freundlich, im Verlauf Bew\u00f6lkungsverdichtung. Ab dem <b>Abend<\/b> Regen, teils schauerartig und gewittrig.<\/p>\n<p>Wetter- und Warnlage: Nach kurzem Zwischenhocheinfluss greifen ab dem <b>Abend<\/b>Ausl\u00e4ufer eines Sturmtiefs bei den Britischen Inseln von Westen her \u00fcber. Dabei wird ein Schwall sehr warmer und feuchter Luft nach Sachsen-Anhalt gef\u00fchrt.<\/p>\n<p>GEWITTER\/STARKREGEN: Ab dem sp\u00e4ten <b>Abend<\/b>von Westen gebietsweise schauerartige, mitunter auch gewittrige Regenf\u00e4lle mit der Gefahr lokalen Starkregens um 20 l\/qm in kurzer Zeit bzw. in wenigen Stunden. Unwetter aufgrund von heftigem Starkregen \u00fcber 30 l\/qm nicht ausgeschlossen! Insbesondere in Verbindung mit Gewittern auch Sturmb\u00f6en um 85 km\/h (Bft 9) und kleink\u00f6rniger Hagel gering wahrscheinlich. Bis <b>Samstagfr\u00fch<\/b> rasch abziehende Regenf\u00e4lle und Gewitter.<\/p>\n<p>WIND: Im Laufe der <b>Nacht<\/b> zum <b>Samstag<\/b> auf dem Brocken zunehmend Sturmb\u00f6en bis 85 km\/h (Bft 9), ab den Fr\u00fchstunden bis <b>Samstagabend<\/b> zeitweise schwere Sturmb\u00f6en bis 100 km\/h (Bft 10). Am <b>Samstag<\/b> tags\u00fcber bis in das Tiefland verbreitet Windb\u00f6en bis 60 km\/h (Bft 7), in freien und windanf\u00e4lligen Lagen st\u00fcrmische B\u00f6en um 70 km\/h (Bft 8).<\/p>\n<p>Detaillierter Wetterablauf: <b>Heute<\/b> fr\u00fch und <b>Vormittag<\/b>heiter, teils wolkig und trocken. Ab dem <b>Mittag<\/b> von Westen her Bew\u00f6lkungsverdichtung, ab dem <b>Abend<\/b>von Westen einsetzender schauerartiger Regen. Bei schwachem s\u00fcd\u00f6stlichem Wind Maxima zwischen 27 und 31, im Harz zwischen 23 und 28 Grad. In der <b>Nacht<\/b> zum <b>Samstag<\/b> zun\u00e4chst bedeckt und weitere schauerartige, teils gewittrige Regenf\u00e4lle. \u00d6rtlich Unwettergefahr! Im Verlauf der zweiten <b>Nachth\u00e4lfte<\/b>abklingende Niederschl\u00e4ge und Auflockerungen. Temperaturr\u00fcckgang auf 21 bis 17 Grad. Von Gewitterb\u00f6en abgesehen, schwacher bis m\u00e4\u00dfiger, auf S\u00fcdwest drehender Wind. Auf dem Brocken Sturmb\u00f6en, in den Fr\u00fchstunden schwere Sturmb\u00f6en.<\/p>\n<p>Am <b>Samstag<\/b> in der ersten Tagesh\u00e4lfte noch weitgehend bedeckt, ab den <b>Mittagsstunden<\/b>Bew\u00f6lkungsr\u00fcckgang und dadurch meist nur noch wolkig, <b>abends<\/b> auch gering bew\u00f6lkt. Ganztags trocken. H\u00f6chsttemperaturen 27 bis 29, im Harz 21 bis 27 Grad. M\u00e4\u00dfiger bis frischer Wind aus S\u00fcdwest mit Windb\u00f6en, exponiert st\u00fcrmischen B\u00f6en, auf dem Brocken teils schwere Sturmb\u00f6en. In der <b>Nacht<\/b> zum <b>Sonntag<\/b> gering bew\u00f6lkt oder klar, trocken. Tiefsttemperaturen 16 bis 13, im Harz bis 11 Grad. Schwacher S\u00fcdwestwind. Brocken Sturm.<\/p>\n<p>Am <b>Sonntag<\/b> wechselnd bew\u00f6lkt, trocken. H\u00f6chstwerte 27 bis 30, im Harz 22 bis 27 Grad. Schwacher, teils m\u00e4\u00dfiger Wind aus S\u00fcdwest. In der <b>Nacht<\/b> zum <b>Montag<\/b> zunehmende Bew\u00f6lkung und von S\u00fcdwesten her aufziehender schauerartiger Regen. Tiefstwerte 16 bis 12 Grad. Schwacher S\u00fcdwestwind.<\/p>\n<p>Am <b>Montag<\/b> bei geschlossener Wolkendecke zeitweise Regen. Bei schwachem s\u00fcdlichem Wind aus s\u00fcdlichen Richtungen Maxima zwischen 23 und 25, im Harz zwischen 18 und 23 Grad. In der <b>Nacht<\/b> zum <b>Dienstag<\/b> rasch abklingende Niederschl\u00e4ge und nachfolgend bei wechselnder Bew\u00f6lkung allenfalls kurze Schauer. Temperaturr\u00fcckgang auf 15 bis 11 Grad. Schwacher S\u00fcdwestwind.<\/p>\n<p>Deutscher Wetterdienst, RWB Leipzig, Adrian Leyser<\/p>\n<h3>Mehr Wetter?<\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ABfox1ElVG\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\">Wettervorhersage<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettervorhersage&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/embed\/#?secret=gvx9ipTL4M#?secret=ABfox1ElVG\" data-secret=\"ABfox1ElVG\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"IghavG5ODi\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/\">Wetterwarnungen<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wetterwarnungen&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/embed\/#?secret=Po0LLO7xiB#?secret=IghavG5ODi\" data-secret=\"IghavG5ODi\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"jTI7CXU7bV\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/\">Wettercam<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettercam&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/embed\/#?secret=SBW8HTZlQW#?secret=jTI7CXU7bV\" data-secret=\"jTI7CXU7bV\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<h2>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle Heute erst freundlich, im Verlauf Bew\u00f6lkungsverdichtung. Ab dem Abend Regen, teils schauerartig und gewittrig. Wetter- und Warnlage: Nach kurzem Zwischenhocheinfluss greifen ab dem AbendAusl\u00e4ufer eines Sturmtiefs bei den Britischen Inseln <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-lobejun-saalekreis-halle-09-08-2019\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[4859,39,4875,4870,4869,4881,4885,4882,4868,4884,4860,4887,5,4883,4873,4872,44,4878,487,4874,4877,4879,4876,63,462,772,628,95,953,2300,4871,4880,4886,1006,231,708,4,94,38,43,96,113],"yst_prominent_words":[2385,1404,11604,1691,1683,1793,1120,2386,2354,2217,9162,3118,2502,2087,2027,1792,1564,2216,2028,1263],"class_list":["post-11402","post","type-post","status-publish","format-standard","hentry","category-wetterblog","tag-beidersee","tag-brachwitz","tag-deutleben","tag-dobis","tag-doeblitz","tag-domnitz","tag-dornitz","tag-doesel","tag-friedrichschwerz","tag-garsena","tag-gimritz","tag-gottgau","tag-halle","tag-kloschwitz","tag-lettewitz","tag-lettin","tag-loebejuen","tag-merbitz","tag-morl","tag-muecheln","tag-nauendorf","tag-neuragozy","tag-neutz-lettewitz","tag-niederschlag","tag-rothenburg","tag-saalefaehren","tag-saalekiez","tag-saalekreis","tag-saalepiraten","tag-saaleschifffahrt","tag-salzmuende","tag-schiepzig","tag-schlettau","tag-taupunkt","tag-temperatur","tag-vorhersage","tag-wetter","tag-wetterbericht","tag-wettervorhersage","tag-wettin","tag-wettin-loebejuen","tag-wind"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-2XU","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11402"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11402\/revisions"}],"predecessor-version":[{"id":11407,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11402\/revisions\/11407"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=11402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=11402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=11402"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=11402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}