{"id":11590,"date":"2020-06-13T09:19:23","date_gmt":"2020-06-13T07:19:23","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=11590"},"modified":"2020-06-13T15:33:25","modified_gmt":"2020-06-13T13:33:25","slug":"unwetterwarnung-gewitter-mit-unwetterpotential-13-06-2020","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/unwetterwarnung-gewitter-mit-unwetterpotential-13-06-2020\/","title":{"rendered":"Unwetterwarnung &#8211; Gewitter mit Unwetterpotential 13.06.2020"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Unwetterwarnung &#8211; Gewitter mit Unwetterpotential<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Datum: 13.06.2020<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uhrzeit: 09:00<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Aktualisierung: 15:30 &#8211; neues Video (DWD)<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Das erste richtig warme Wochenende in 2020 bringt auch gleich die passenden Gewitter mit. Heute erwarten wir in Brachwitz Temperaturen bis 29 Grad, bei schw\u00fcler Auspr\u00e4gung. Ab dem Nachmittag werden lokal Gewitter mit Starkregen auftreten. Dabei k\u00f6nnen in kurzer Zeit bis 25 Liter pro Quadratmeter fallen und \u00fcber wenige Stunden sich die Niederschlagsmengen \u00f6rtlich auf 60 Liter pro Quadratmeter aufsummieren(das ist als Unwetter deklariert). Auch Sturmb\u00f6en in Gewittern\u00e4he bis 90 km\/h sind m\u00f6glich. Die Prognosen bez\u00fcglich Hagel sind noch nicht eindeutig, gehen aber von bis zu 3 cm gro\u00dfen Hagel aus, auch wenn nur selten und \u00f6rtlich begrenzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Also genie\u00dft das Wetter bis zum fr\u00fchen Nachmittag und r\u00e4umt dann alles weg, was wegfliegen kann. Passt auf euch auf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Achtet auf die Aktualisierungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&nbsp;<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Wetterwarnung (von 06:30 Uhr)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Bei geringen Luftdruckgegens\u00e4tzen bestimmen feuchtwarme Luftmassen das Wettergeschehen in Sachsen-Anhalt. GEWITTER (UNWETTER): Heute und am Sonntag \u00f6rtlich schwere Gewitter mit teils heftigem Starkregen \u00fcber 25 l\/qm in kurzer Zeit oder \u00fcber 60 l\/qm aufsummiert \u00fcber mehrere Stunden (extremes UNWETTER), Sturmb\u00f6en bis 90 km\/h (Bft 10) und Hagel.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1499\" height=\"2048\" data-attachment-id=\"13104\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/a3365061-14a2-4c09-83cd-5bed52e3d585\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585.jpeg\" data-orig-size=\"1499,2048\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Unwetterwarnung Brachwitz\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585-750x1024.jpeg\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585.jpeg\" alt=\"Unwetterwarnung, Gewitter, Beidersee, brachwitz, dauerregen, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, gewitter, Gimritz, Gottgau, hagel, Halle, halle saale, H\u00e4ndel, Heide-Nord, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, M\u00f6derau, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, orkanb\u00f6en, Rothenburg, saalekreis, Sachen-Anhalt, Salzm\u00fcnde, Schiepzig, Schlettau, Sennewitz, starkregen, Taupunkt, Temperatur, Trotha, unwetter, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" class=\"wp-image-13104\" title=\"Unwetterwarnung, Gewitter, Beidersee, brachwitz, dauerregen, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, gewitter, Gimritz, Gottgau, hagel, Halle, halle saale, H\u00e4ndel, Heide-Nord, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, M\u00f6derau, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, orkanb\u00f6en, Rothenburg, saalekreis, Sachen-Anhalt, Salzm\u00fcnde, Schiepzig, Schlettau, Sennewitz, starkregen, Taupunkt, Temperatur, Trotha, unwetter, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585.jpeg 1499w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585-220x300.jpeg 220w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585-750x1024.jpeg 750w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585-768x1049.jpeg 768w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585-1124x1536.jpeg 1124w\" sizes=\"auto, (max-width: 1499px) 100vw, 1499px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Unwetter-Video DWD<\/h2>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/f5f4AbSeJ1U\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Synoptische \u00dcbersicht<\/h2>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Vw5N430CzP\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/synoptische-uebersicht\/\">Synoptische \u00dcbersicht<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Synoptische \u00dcbersicht&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/synoptische-uebersicht\/embed\/#?secret=6SD2LvGJoL#?secret=Vw5N430CzP\" data-secret=\"Vw5N430CzP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Weiterf\u00fchrende Links<\/h3>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"bnzfBgpBN2\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/cape-faktor-und-lifted-index\/\">CAPE Faktor und Lifted Index<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;CAPE Faktor und Lifted Index&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/cape-faktor-und-lifted-index\/embed\/#?secret=7spPjjxFGw#?secret=bnzfBgpBN2\" data-secret=\"bnzfBgpBN2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"v3tCp5UXV0\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/aktuelle-grafiken\/\">Aktuelle Grafiken<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Aktuelle Grafiken&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/aktuelle-grafiken\/embed\/#?secret=gWBkmh3aBx#?secret=v3tCp5UXV0\" data-secret=\"v3tCp5UXV0\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"VTB42BoBbR\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/\">Wetterwarnungen<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wetterwarnungen&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/embed\/#?secret=yUZTfxQP34#?secret=VTB42BoBbR\" data-secret=\"VTB42BoBbR\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ZdZN3mo8Nd\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/regenradar\/\">Regenradar<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Regenradar&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/regenradar\/embed\/#?secret=MKuthGQPwr#?secret=ZdZN3mo8Nd\" data-secret=\"ZdZN3mo8Nd\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"LsWWG26xDz\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/blitzortung\/\">Blitzortung<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Blitzortung&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/blitzortung\/embed\/#?secret=48Iir4GRjr#?secret=LsWWG26xDz\" data-secret=\"LsWWG26xDz\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wetterstation-brachwitz\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"QjhjSgzDtP\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/\">Wettercam<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettercam&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/embed\/#?secret=fYyb7i5FmL#?secret=QjhjSgzDtP\" data-secret=\"QjhjSgzDtP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Unwetterwarnung &#8211; Gewitter mit Unwetterpotential Datum: 13.06.2020 Uhrzeit: 09:00 Aktualisierung: 15:30 &#8211; neues Video (DWD) Das erste richtig warme Wochenende in 2020 bringt auch gleich die passenden Gewitter mit. Heute erwarten wir in Brachwitz Temperaturen bis 29 Grad, bei schw\u00fcler <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/unwetterwarnung-gewitter-mit-unwetterpotential-13-06-2020\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":13104,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[4859,39,236,4875,4870,4869,4881,4885,4882,4868,4884,41,4860,4887,93,5,97,4848,5006,4883,4873,4872,44,4878,5005,487,4874,4877,4879,4876,63,452,462,95,4847,4871,4880,4886,5008,106,1006,231,5007,71,708,4,94,38,43,96,113],"yst_prominent_words":[5507,5876,9830,11171,5414,3267,4466,5614,5506,2162,2157,4100,2759,2163,4481,1414,3129],"class_list":["post-11590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-beidersee","tag-brachwitz","tag-dauerregen","tag-deutleben","tag-dobis","tag-doeblitz","tag-domnitz","tag-dornitz","tag-doesel","tag-friedrichschwerz","tag-garsena","tag-gewitter","tag-gimritz","tag-gottgau","tag-hagel","tag-halle","tag-halle-saale","tag-haendel","tag-heide-nord","tag-kloschwitz","tag-lettewitz","tag-lettin","tag-loebejuen","tag-merbitz","tag-moederau","tag-morl","tag-muecheln","tag-nauendorf","tag-neuragozy","tag-neutz-lettewitz","tag-niederschlag","tag-orkanboeen","tag-rothenburg","tag-saalekreis","tag-sachen-anhalt","tag-salzmuende","tag-schiepzig","tag-schlettau","tag-sennewitz","tag-starkregen","tag-taupunkt","tag-temperatur","tag-trotha","tag-unwetter","tag-vorhersage","tag-wetter","tag-wetterbericht","tag-wettervorhersage","tag-wettin","tag-wettin-loebejuen","tag-wind"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2020\/06\/A3365061-14A2-4C09-83CD-5BED52E3D585.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-30W","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11590"}],"version-history":[{"count":2,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11590\/revisions"}],"predecessor-version":[{"id":13108,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/11590\/revisions\/13108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/13104"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=11590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=11590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=11590"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=11590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}