{"id":14534,"date":"2021-03-08T16:23:58","date_gmt":"2021-03-08T14:23:58","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=14534"},"modified":"2021-03-08T16:24:00","modified_gmt":"2021-03-08T14:24:00","slug":"erster-sturm-des-jahres","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/erster-sturm-des-jahres\/","title":{"rendered":"Erster Sturm des Jahres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Zum Donnerstag, den 11.03.2021, deutet sich eine recht fl\u00e4chige Sturmlage \u00fcber Deutschland an. Welche Faktoren die Heftigkeit des Sturms bei uns ggf. beeinflussen, soll hier kurz dargelegt werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am letzten Donnerstag (04.03.2021) traten doch recht h\u00e4ufig Gewitter vor allem in der Mitte Deutschlands auf, die teils von Graupel oder kleinem Hagel sowie kleinr\u00e4umig auch st\u00fcrmischen B\u00f6en um 70 km\/h begleitet waren. Diese vom Charakter und der Intensit\u00e4t her eher winterliche Gewitter l\u00e4uteten bereits die Gewittersaison in Deutschland ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun deutet eine lebhafte Weststr\u00f6mung \u00fcber dem Nordatlantik darauf hin, dass sich in den n\u00e4chsten Tagen eine veritable Sturmlage \u00fcber Teilen West- und Mitteleuropa entwickeln kann. Klar, der Monat M\u00e4rz ist in den n\u00f6rdlichen Breiten klimatologisch gesehen noch ein Wintermonat. Andererseits endet im M\u00e4rz die Polarnacht dort, und die Strahlungserw\u00e4rmung vor allem der Landmassen, verz\u00f6gert auch der Atmosph\u00e4re und Meeresoberfl\u00e4chen in den mittleren Breiten, macht erste Fortschritte. Dadurch erh\u00f6hen sich grob gesagt die S\u00fcd-Nordkontraste bei der Temperatur und beim Luftdruck. So sind die Grundvoraussetzungen bzw. auch die Erfordernisse gegeben, diese Gegens\u00e4tze irgendwie abzubauen. Dies geschieht in der Natur am effektivsten und schnellsten \u00fcber die Turbulenz. Der aufmerksame Leser ahnt bereits, worauf diese Anspielung hinausl\u00e4uft. Ja, die Neigung zu vor\u00fcbergehend st\u00fcrmischen Zeiten im atlantisch-europ\u00e4ischen Raum ist daher nicht untypisch f\u00fcr den Monat M\u00e4rz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rechtzeitig zur Wochenmitte etabliert sich nun ein kr\u00e4ftiger Tiefdruckkomplex zwischen den Britischen Inseln und Island. Um dieses zentrale Drehzentrum sollen mehrere kleinr\u00e4umige Tiefs herumgesteuert werden, die idealen N\u00e4hrboden f\u00fcr ihre Vertiefung (eins davon mit prognostiziertem Kerndruck von rund 960 hPa am Donnerstag, 11.03.2021, 12 Uhr UTC) am Rande einer straffen Frontalzone weit drau\u00dfen auf dem Atlantik finden. Jetzt kommt die entscheidende Frage f\u00fcr uns hier in Mitteleuropa. Wo erreicht einer dieser kleinen und flotten Tiefs (daher auch Schnelll\u00e4ufer genannt) seine st\u00e4rkste Auspr\u00e4gung?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derzeit sieht es so aus, als ob die Zugbahnen etwas n\u00f6rdlicher bzw. nordwestlicher in Richtung Nordmeer verlaufen. Das w\u00fcrde bedeuten, dass der st\u00e4rkste Druckgradient und damit st\u00e4rkste Wind nicht gerade bei uns auftritt. Ursache daf\u00fcr ist hoher Luftdruck, der sich im Vorfeld von Mitteleuropa bis nach Skandinavien aufbaut und an dem die st\u00e4rksten Entwicklungen herumgeleitet werden bzw. zun\u00e4chst auch etwas abprallen. Nichtsdestotrotz wird der hohe Luftdruck im Verlauf nach Osten abgedr\u00e4ngt und die Str\u00f6mung gl\u00e4ttet sich bei uns mit eher westlicher Grundstr\u00f6mung.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entwarnung ist damit auch nicht gemeint, zumindest liegen wir weiterhin im Randbereich der Tiefdruckgebiete \u00fcber dem Ostatlantik und S\u00fcdskandinavien. F\u00fcr den Donnerstag (11.03.2021) bedeutet das f\u00fcr Deutschland mit Ausnahme des Ostens und S\u00fcdostens recht fl\u00e4chig B\u00f6en der St\u00e4rke Bft 8 bis 9 (35 bis 45 Knoten bzw. rund 65 bis 85 km\/h). Bevorzugt im Westen und Nordwesten sind auch h\u00e4ufiger B\u00f6en der St\u00e4rke Bft 9 bis 10 (45 bis 55 Knoten bzw. rund 85 bis 100 km\/h), bevorzugt im Nordseeumfeld vereinzelt auch orkanartige B\u00f6en der St\u00e4rke 11 (57 bis 60 Knoten bzw. etwa 105 bis 110 km\/h) m\u00f6glich. Im h\u00f6heren Bergland dagegen sind orkanartige B\u00f6en und Orkanb\u00f6en der St\u00e4rke Bft 11 bis 12 (56 bis \u00fcber 65 Knoten bzw. 105 bis \u00fcber 120 km\/h) zu erwarten. N\u00e4here Infos hierzu finden Sie in der beigef\u00fcgten Grafik (Prognose des ICON-Modells des DWD f\u00fcr Donnerstag, 11.03.2021, 15 Uhr UTC.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So stellt sich die Lage bisher dar, weitere Updates zum Thema werden folgen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dipl.-Met. Dr. Jens Bonewitz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 07.03.2021<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Copyright (c) Deutscher Wetterdienst<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"959\" height=\"770\" data-attachment-id=\"14536\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/erster-sturm-des-jahres\/ea91539d-89c1-4b16-b0ab-c70ef7d5816b\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/EA91539D-89C1-4B16-B0AB-C70EF7D5816B.png\" data-orig-size=\"959,770\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"EA91539D-89C1-4B16-B0AB-C70EF7D5816B\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/EA91539D-89C1-4B16-B0AB-C70EF7D5816B.png\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/EA91539D-89C1-4B16-B0AB-C70EF7D5816B.png\" alt=\"\" class=\"wp-image-14536\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/EA91539D-89C1-4B16-B0AB-C70EF7D5816B.png 959w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/EA91539D-89C1-4B16-B0AB-C70EF7D5816B-300x241.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/EA91539D-89C1-4B16-B0AB-C70EF7D5816B-768x617.png 768w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Zum Donnerstag, den 11.03.2021, deutet sich eine recht fl\u00e4chige Sturmlage \u00fcber Deutschland an. Welche Faktoren die Heftigkeit des Sturms bei uns ggf. beeinflussen, soll hier kurz dargelegt werden.&nbsp; Am letzten Donnerstag (04.03.2021) traten doch recht h\u00e4ufig Gewitter vor allem in <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/erster-sturm-des-jahres\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":14535,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[213,71],"yst_prominent_words":[5706,5741,5989,1216,1411,2509,5614,3312,2223,8910,1512,3119,6256,2132],"class_list":["post-14534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-sturm","tag-unwetter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2021\/03\/9F805F80-A628-4D80-9312-FD0F4453154A.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-3Mq","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/14534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=14534"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/14534\/revisions"}],"predecessor-version":[{"id":14537,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/14534\/revisions\/14537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/14535"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=14534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=14534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=14534"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=14534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}