{"id":1676,"date":"2015-10-11T13:03:09","date_gmt":"2015-10-11T11:03:09","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=1676"},"modified":"2015-10-11T13:03:09","modified_gmt":"2015-10-11T11:03:09","slug":"farbspektakel-am-himmel","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/farbspektakel-am-himmel\/","title":{"rendered":"Farbspektakel am Himmel"},"content":{"rendered":"<h2>Farbspektakel am Himmel<\/h2>\n<div style=\"text-align: justify;\">Bei geeigneten Wetterbedingungen kann oftmals das Morgen- oder Abendrot beobachtet werden. Wie kommt es, dass der tags\u00fcber noch azurblaue Himmel beim abendlichen Sonnenuntergang in einem malerischen Rot erscheint? Was sind die physikalischen Hintergr\u00fcnde dieses Ph\u00e4nomens?<\/p>\n<p>Dieses Ph\u00e4nomen beruht auf den physikalischen Gesetzen der Lichtstreuung. Im physikalischen Sinne stellt das Licht eine elektromagnetische Welle dar. Diese Welle wird durch kleine Hindernisse von ihrer urspr\u00fcnglichen Ausbreitungsrichtung abgelenkt, was als Streuung bezeichnet wird. In der Atmosph\u00e4re stellen diese Hindernisse z. B. Luftmolek\u00fcle, Aerosolteilchen (Ru\u00df, Staub, Sandk\u00f6rner, etc.) oder kleinste Wassertr\u00f6pfchen dar. Der Streuprozess ist zum einen abh\u00e4ngig von der Wellenl\u00e4nge des Lichtes und zum anderen vom Verh\u00e4ltnis der Wellenl\u00e4nge zur Gr\u00f6\u00dfe der Partikel, an denen das Licht gestreut wird.<\/p>\n<p>Im speziellen Fall der Blauf\u00e4rbung des Himmels oder bei der Entstehung des Abendrots wird das Licht an Luftmolek\u00fclen gestreut, deren Durchmesser viel kleiner ist als die Wellenl\u00e4nge des Lichtes. Dieser Prozess wird durch die klassische Theorie nach Rayleigh beschrieben. Diese besagt unter anderem, dass die St\u00e4rke der Streuung des Sonnenlichtes umgekehrt proportional zur 4. Potenz der Wellenl\u00e4nge ist. Vereinfacht gesagt bedeutet dies, dass die kurzwellige Sonnenstrahlung sehr viel st\u00e4rker gestreut wird als die langwellige Strahlung. In der Atmosph\u00e4re gibt es neben kleinen Staubpartikeln, Wassertr\u00f6pfchen und sonstigen Fremdstoffen, vor allem kleine Gasmolek\u00fcle wie z. B. Stickstoff. Die Konzentration dieser Gasmolek\u00fcle ist in der Atmosph\u00e4re gleichm\u00e4\u00dfig verteilt. Zudem liegt der Durchmesser dieser Molek\u00fcle im Pikometer-Bereich (Pikometer ist ein milliardstel Millimeter) und ist damit im Vergleich zur Wellenl\u00e4nge des Sonnenlichts (Nanometer-Bereich, ein millionstel Millimeter) um einen Faktor 1000 kleiner. Somit sind die oben beschriebenen Voraussetzungen der Rayleigh-Streuung erf\u00fcllt.<\/p>\n<p>Das Sonnenlicht, welches wir als wei\u00dfes Licht wahrnehmen, stellt eine Mischung aller farbigen Anteile (Spektralfarben) dar. Dabei weist der blaue Anteil die kleinste und der rote Anteil die gr\u00f6\u00dfte Wellenl\u00e4nge auf. Tags\u00fcber m\u00fcssen die Sonnenstrahlen nur einen vergleichsweise kurzen Weg durch die Atmosph\u00e4re zur\u00fccklegen. Somit gelangen alle Farbanteile des gestreuten Lichts direkt oder indirekt zum Beobachter am Erdboden, wobei der blaue Anteil der Sonnenstrahlung am st\u00e4rksten gestreut wird. Daraus resultiert die Blauf\u00e4rbung des Himmels. Bei Sonnenaufgang und -untergang muss die Sonnenstrahlung einen sehr langen Weg durch die Atmosph\u00e4re bis hin zum Beobachter zur\u00fccklegen. Bis das Licht den Betrachter erreicht, wird bereits ein Gro\u00dfteil des blauen Lichts heraus gestreut. Deshalb gelangt \u00fcberwiegend der rote und gelbe Anteil des Sonnenlichts bis zum Beobachter und f\u00fchrt schlussendlich zu einem roten Erscheinungsbild der Sonne bzw. zur r\u00f6tlichen Einf\u00e4rbung des Himmels am Horizont. Besonders spektakul\u00e4r ist es, wenn Wolken oder Berge (Alpengl\u00fchen) von diesem roten Sonnenlicht beleuchtet werden und so das Abend- bzw. das Morgenrot intensiver erscheinen lassen.<\/p>\n<p>Richten Sie doch heute Abend einfach den Blick in Richtung Westen, vielleicht haben Sie bei geeigneten Wetterbedingungen das Gl\u00fcck das Abendrot zu beobachten.<\/p>\n<p>M.Sc.-Met. Andreas W\u00fcrtz Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 11.10.2015 Copyright (c) <a href=\"http:\/\/www.dwd.de\" target=\"_blank\">Deutscher Wetterdienst<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Farbspektakel am Himmel Bei geeigneten Wetterbedingungen kann oftmals das Morgen- oder Abendrot beobachtet werden. Wie kommt es, dass der tags\u00fcber noch azurblaue Himmel beim abendlichen Sonnenuntergang in einem malerischen Rot erscheint? Was sind die physikalischen Hintergr\u00fcnde dieses Ph\u00e4nomens? Dieses Ph\u00e4nomen <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/farbspektakel-am-himmel\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":914,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[218,305],"yst_prominent_words":[],"class_list":["post-1676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-herbst","tag-sonnenuntergang"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/07\/summer-789974_1280.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-r2","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/1676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=1676"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/1676\/revisions"}],"predecessor-version":[{"id":1677,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/1676\/revisions\/1677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/914"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=1676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=1676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=1676"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=1676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}