{"id":1678,"date":"2015-10-12T05:26:15","date_gmt":"2015-10-12T03:26:15","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=1678"},"modified":"2015-10-12T05:26:15","modified_gmt":"2015-10-12T03:26:15","slug":"wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-80","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-80\/","title":{"rendered":"Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle"},"content":{"rendered":"<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n<p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1679\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-80\/image-55\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/10\/image7.png\" data-orig-size=\"828,302\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Wettervorhersage 12.10.2015\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/10\/image7.png\" class=\"alignnone wp-image-1679 size-full\" title=\"Wettervorhersage 12.10.2015\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/10\/image7.png\" alt=\"Wettervorhersage 12.10.2015\" width=\"828\" height=\"302\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/10\/image7.png 828w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/10\/image7-300x109.png 300w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Tags\u00fcber viel Sonnenschein. Nachts Wolkenaufzug, vereinzelt Frost und Nebel.<\/p>\n<p>Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Sachsen-Anhalt befindet sich im Einflussbereich eines Hochs \u00fcber Skandinavien. Dabei flie\u00dft von Nordosten her k\u00fchle und trockene Luft ein.<\/p>\n<p>Heute Fr\u00fch tritt verbreitet leichter Frost bis -3, im Harz bis -4 Grad auf. In Bodenn\u00e4he muss mit Frost bis -5, im Harz bis -7 Grad gerechnet werden. In der Nacht zum Dienstag tritt nur noch vereinzelt leichter Frost bis -1 Grad, im Harz bis -3 Grad auf. In Bodenn\u00e4he ist verbreitet mit leichtem Frost zwischen -1 und -4 Grad zu rechnen. In T\u00e4lern und Senken bilden sich in der Nacht zum Dienstag vereinzelt Nebelfelder, teils mit Sichtweiten unter 150 m und meist mit Reifbildung an Gegenst\u00e4nden. Sie l\u00f6sen sich im Vormittagsverlauf auf.<\/p>\n<p>Detaillierter Wetterablauf: Heute Fr\u00fch ist es verbreitet klar. Im Tagesverlauf scheint bei nur wenigen Wolken die Sonne und es bleibt trocken. Bei schwachem bis m\u00e4\u00dfigem Nordost- bis Ostwind liegen die H\u00f6chsttemperaturen zwischen 6 und 9, im Harz zwischen 2 und 6 Grad. In der Nacht zum Dienstag verdichten sich die Wolken, in der zweiten Nachth\u00e4lfte ist es dann bereits vielfach stark bew\u00f6lkt. Niederschlag f\u00e4llt aber nicht. Stellenweise kann sich Nebel bilden. Der Wind weht schwach aus Ost bis Nordost. Die Temperaturen gehen auf 1 bis -1, im Harz bis -3, in Bodenn\u00e4he bis -4 Grad zur\u00fcck.<\/p>\n<p>Am Dienstag ist der Himmel meist stark bew\u00f6lkt und die Sonne zeigt sich nur sehr selten. Vor allem in der Altmark kann etwas Regen oder Spr\u00fchregen fallen, meist bleibt es aber trocken. Schwacher bis m\u00e4\u00dfiger Wind aus nord\u00f6stlichen Richtungen l\u00e4sst die Temperaturen nur auf 4 bis 7, im Harz auf 0 bis 4 Grad steigen. In der Nacht zum Mittwoch ist es \u00fcberwiegend stark bew\u00f6lkt und es f\u00e4llt etwas Regen, im Oberharz auch Schnee. Bei Tiefsttemperaturen zwischen 3 und 1, im Harz zwischen 1 und -4 Grad weht nur schwacher Wind aus n\u00f6rdlichen Richtungen.<\/p>\n<p>Am Mittwoch ist es \u00fcberwiegend bedeckt und es kommt zu weiteren leichten Niederschl\u00e4gen. Schnee f\u00e4llt nur auf dem Brocken. Bei schwachem Nordostwind werden 4 bis 7, im Harz -1 bis 4 Grad erreicht. In der Nacht zum Donnerstag ist es wechselnd, teils auch stark bew\u00f6lkt und \u00fcberwiegend trocken. Die Minima liegen zwischen 3 und 1, im Harz zwischen 1 und -1 Grad. Es weht schwacher Nordwind.<\/p>\n<p>Am Donnerstag bleibt die Wolkendecke geschlossen und immer wieder f\u00e4llt leichter Regen, auf dem Brocken f\u00e4llt etwas Schnee. Bei meist schwachem n\u00f6rdlichem Wind werden Maxima zwischen 6 und 9, im Harz zwischen 3 und 6 Grad erwartet. In der Nacht zum Freitag bleibt es bei einem bedeckten Himmel weiterhin unbest\u00e4ndig mit zeitweiligen Regenf\u00e4llen. Die Luft k\u00fchlt auf 5 bis 3, im Harz bis 1 Grad ab. Es weht m\u00e4\u00dfiger Nordwind.<\/p>\n<p>Deutscher Wetterdienst, RWB Leipzig, Magdalena Bertelmann<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle &nbsp; Tags\u00fcber viel Sonnenschein. Nachts Wolkenaufzug, vereinzelt Frost und Nebel. Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Sachsen-Anhalt befindet sich im Einflussbereich eines Hochs \u00fcber Skandinavien. Dabei flie\u00dft von Nordosten her k\u00fchle und trockene <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-80\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[39,5,95,38,96],"yst_prominent_words":[],"class_list":["post-1678","post","type-post","status-publish","format-standard","hentry","category-wetterblog","tag-brachwitz","tag-halle","tag-saalekreis","tag-wettervorhersage","tag-wettin-loebejuen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-r4","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/1678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=1678"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/1678\/revisions"}],"predecessor-version":[{"id":1680,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/1678\/revisions\/1680"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=1678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=1678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=1678"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=1678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}