{"id":2359,"date":"2016-01-12T15:35:14","date_gmt":"2016-01-12T13:35:14","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=2359"},"modified":"2016-01-12T15:35:14","modified_gmt":"2016-01-12T13:35:14","slug":"manege-frei-fuer-kalte-winterluft","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/manege-frei-fuer-kalte-winterluft\/","title":{"rendered":"Manege frei f\u00fcr kalte Winterluft!"},"content":{"rendered":"<h2>Manege frei f\u00fcr kalte Winterluft!<\/h2>\n<div style=\"text-align: justify;\">Das heutige Thema des Tages wird vermutlich all denen gefallen, die sich zur Gruppe der leidenschaftlichen Winterfans, Skifahrer, Rodler oder Schneemannbauer z\u00e4hlen &#8211; oder aus sonstigen Gr\u00fcnden den wei\u00dfen Firn und frostige Temperaturen lieben. F\u00fcr Wintermuffel hingegen sind die Nachrichten wohl alles andere als positiv; ihnen wird an diesem Punkt die einmalige Gelegenheit geboten, aus dem Text auszusteigen&#8230;<\/p>\n<p>Die derzeitige Ausgangslage f\u00fcr das nahende Winterintermezzo ist schnell erz\u00e4hlt: Tief CAROLINA befindet sich derzeit \u00fcber der Nordsee und schaufelt best\u00e4ndig feuchte, aber noch milde Atlantikluft nach Deutschland. Gar nicht so weit entfernt von uns befindet sich hingegen richtig kalte Festlandsluft: In Skandinavien und dem Norden Russlands herrscht schon seit Tagen klirrende K\u00e4lte bei ca. minus 20 Grad Celsius. Diese konnte bisher aber noch nicht nach S\u00fcden gelangen, denn CAROLINA (die sich inzwischen mit dem \u00f6stlich von uns liegenden Tiefdruckgebiet DANIELLA verbunden hat), verhindert mit ihrem Drehsinn gegen den Uhrzeigersinn bisher das Einstr\u00f6men der Frostluft nach Deutschland (siehe Abbildung links).<\/p>\n<p>In den n\u00e4chsten Tagen \u00e4ndert sich die gro\u00dfr\u00e4umige Str\u00f6mungskonstellation jedoch, denn das steuernde Zentraltief verlagert sein Zentrum weiter in Richtung Nordosteuropa. &#8222;Ja und?&#8220; mag sich jetzt der ein oder andere Leser fragen, &#8222;was bedeutet das f\u00fcr uns?&#8220;. &#8211; Nun ja, durch den Abzug von CAROLINA nach Osten werden quasi die Schranken f\u00fcr die kalte Polarluft ge\u00f6ffnet, die daraufhin ungehindert \u00fcber Polen und die Ostsee her zu uns nach Deutschland vorsto\u00dfen kann (siehe Abbildung rechts).<\/p>\n<p>Was daraus folgt, liegt auf der Hand: Die Temperaturen gehen auf Talfahrt bis in den Frostbereich, zun\u00e4chst im Nordosten des Landes (ab Donnerstag), einige Tage sp\u00e4ter dann auch nahezu in allen anderen Landesteilen (Sonntag). Vor allem nachts m\u00fcssen sich &#8222;Frostbeulen&#8220; am kommenden Wochenende dick einpacken: Bei Tiefstwerten zwischen -5 und -10 Grad, \u00f6rtlich auch darunter, wird es im ganzen Land eisig kalt.<\/p>\n<p>Und wie sind die Prognosen f\u00fcrs Schneemannbauen? Gut! Der Schneefall beschr\u00e4nkt sich zwar zun\u00e4chst haupts\u00e4chlich auf die Mittelgebirge und Norddeutschland, aber die Niederschl\u00e4ge gehen in den n\u00e4chsten Tagen auch im Flachland zunehmend in Schnee \u00fcber. W\u00e4hrend in den Niederungen mancherorts wohl nur mal ein paar Flocken vom Himmel rieseln, stehen im Bergland teils kr\u00e4ftige Schneef\u00e4lle auf dem Programm, dort kann in einigen Staulagen bis zu einem halben Meter Neuschnee fallen. Spazierg\u00e4nger sollten sich also nicht erschrecken, wenn sie pl\u00f6tzlich einem gigantischen Schneemann gegen\u00fcber stehen. Und mit den frostigen Temperaturen am Wochenende sind beste Konservierungsbedingungen f\u00fcr Schneebauten jeglicher Art gegeben!<\/p>\n<p>Wie lange sich das Winterwetterbei uns halten kann, ist noch unsicher.F\u00fcr die Wintermuffel unter der Leserschaft, die bis hierhin durchgehalten haben, sei eine (zwar wenig tr\u00f6stliche aber ernstgemeinte) Bemerkung am Schluss erlaubt: Der n\u00e4chste Sommer kommt bestimmt!<\/p>\n<p>Dipl.-Met. Magdalena Bertelmann Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 12.01.2016<\/p>\n<p>Copyright (c) Deutscher Wetterdienst<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Manege frei f\u00fcr kalte Winterluft! Das heutige Thema des Tages wird vermutlich all denen gefallen, die sich zur Gruppe der leidenschaftlichen Winterfans, Skifahrer, Rodler oder Schneemannbauer z\u00e4hlen &#8211; oder aus sonstigen Gr\u00fcnden den wei\u00dfen Firn und frostige Temperaturen lieben. F\u00fcr <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/manege-frei-fuer-kalte-winterluft\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1710,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[388,297,402],"yst_prominent_words":[],"class_list":["post-2359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-388","tag-winter","tag-winter-2016"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2015\/10\/winterreifen-e1447843854386.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-C3","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2359"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2359\/revisions"}],"predecessor-version":[{"id":2360,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2359\/revisions\/2360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/1710"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2359"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=2359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}