{"id":2417,"date":"2016-01-20T09:50:45","date_gmt":"2016-01-20T07:50:45","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=2417"},"modified":"2016-01-20T09:50:45","modified_gmt":"2016-01-20T07:50:45","slug":"wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-146","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-146\/","title":{"rendered":"Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2418\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-146\/image-168\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20.png\" data-orig-size=\"828,302\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Wettervorhersage 20.01.2016\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20.png\" class=\"alignnone size-full wp-image-2418\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20.png\" alt=\"Wettervorhersage 20.01.2016\" width=\"828\" height=\"302\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20.png 828w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20-300x109.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20-768x280.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Gebietsweise leichter Schneefall.<\/p>\n<p>Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Von Norden her \u00fcberquert die Front eines von S\u00fcdschweden ins Baltikum ziehenden Tiefs Sachsen-Anhalt.<\/p>\n<p>Heute gibt es gebietsweise leichten Schneefall, der im Tagesverlauf von Norden her allm\u00e4hlich abklingt. Dabei werden vor allem in den n\u00f6rdlichen Landesteilen nur geringe Neuschneeh\u00f6hen um 1 cm erwartet, nach S\u00fcden hin ist mit bis zu 3 cm und vor allem im Harz auch bis 5 cm Neuschnee zu rechnen. Es kommt streckenweise zu entsprechender Schneegl\u00e4tte, zum Teil herrscht auch weiterhin leichter Dauerfrost. In der Nacht zum Donnerstag f\u00e4llt in den s\u00fcdlichen Landesteilen zun\u00e4chst noch etwas Schnee, der zu Gl\u00e4tte f\u00fchren kann. Auch sonst muss mit Gl\u00e4tte durch \u00fcberfrierende N\u00e4sse oder durch Reif gerechnet werden. Zudem tritt leichter, teils m\u00e4\u00dfiger Frost auf.<\/p>\n<p>Detaillierter Wetterablauf: Heute Vormittag ist es meist stark bew\u00f6lkt und gebietsweise kommt es meist zu leichten Schneef\u00e4llen, die im Tagesverlauf allm\u00e4hlich von Norden abklingen. Die Neuschneemengen liegen im Norden meist um 1 cm, in den s\u00fcdlichen Landesteilen k\u00f6nnen bis zu 3 cm und im Harz bis 5 cm erwartet werden. Der Wind weht schwach aus West bis Nordwest. Die Temperatur liegt zwischen -1 und 2, im Harz zwischen -4 und -1 Grad. In der Nacht zum Donnerstag ist es anfangs stark bew\u00f6lkt und gelegentlich f\u00e4llt vor allem nach S\u00fcden hin noch etwas Schnee. Im Laufe der Nacht klingen die Niederschl\u00e4ge auch dort meist ab und von Norden her kann es Auflockerungen geben. Die Temperaturen fallen auf -3 bis -6, im Harz teils auf -10 Grad.<\/p>\n<p>Am Donnerstag ist es wechselnd, im Tagesverlauf h\u00e4ufiger gering bew\u00f6lkt und es bleibt \u00fcberwiegend niederschlagsfrei. Der Wind weht schwach um West und die Temperatur erreicht ein Maximum zwischen -3 und -1, im Harz zwischen -5 und -3 Grad. In der Nacht zum Freitag ist es h\u00e4ufig gering bew\u00f6lkt oder klar, streckenweise kann sich allerdings Nebel bilden. Bei schwachem Wind aus s\u00fcdwestlichen Richtungen f\u00e4llt die Temperatur auf kalte -8 bis -11 Grad.<\/p>\n<p>Am Freitag ist es nach Nebelaufl\u00f6sung zun\u00e4chst meist gering bew\u00f6lkt oder gar sonnig. Im Laufe des Nachmittages zieht von Westen allm\u00e4hlich dichtere Bew\u00f6lkung auf, es bleibt aber noch trocken. Der Wind weht schwach aus s\u00fcdlichen Richtungen. Die Temperatur steigt auf -4 bis -1 Grad. In der Nacht zum Samstag verdichtet sich die Bew\u00f6lkung von Westen weiter und Niederschl\u00e4ge kommen auf, die anfangs noch teils als Schnee, im weiteren Verlauf aber h\u00e4ufig als Schneeregen oder Regen niedergehen. Auf den gefrorenen B\u00f6den besteht dann die Gefahr von Glatteisbildung. Der Wind weht schwach bis m\u00e4\u00dfig aus s\u00fcdlichen Richtungen. Die Tiefstwerte liegen bei -5 bis -10 Grad, wobei es im Verlauf der Nacht von Westen her aber deutlich milder wird.<\/p>\n<p>Am Samstag \u00fcberquert ein Wolken- und Niederschlagsband die Region, dabei f\u00e4llt meist Regen. Dadurch besteht streckenweise noch weiterhin Glatteisgefahr. Der Wind weht aus S\u00fcdwest und dreht tags\u00fcber auf West. Die Temperatur steigt auf 1 bis 4 Grad an. In der Nacht zum Sonntag ist es meist stark bew\u00f6lkt. Zeitweise f\u00e4llt Regen, der aber allm\u00e4hlich abklingt. Der Wind weht schwach bis m\u00e4\u00dfig aus West. Die Temperatur liegt bei +1 bis -1, im Harz bei -2 Grad.<\/p>\n<p>Deutscher Wetterdienst, RWB Leipzig, Florian Engelmann<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle &nbsp; Gebietsweise leichter Schneefall. Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Von Norden her \u00fcberquert die Front eines von S\u00fcdschweden ins Baltikum ziehenden Tiefs Sachsen-Anhalt. Heute gibt es gebietsweise leichten Schneefall, der im <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-146\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[39,5,95,38,96],"yst_prominent_words":[],"class_list":["post-2417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-brachwitz","tag-halle","tag-saalekreis","tag-wettervorhersage","tag-wettin-loebejuen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/01\/image-20.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-CZ","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2417"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2417\/revisions"}],"predecessor-version":[{"id":2419,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2417\/revisions\/2419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/2418"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2417"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=2417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}