{"id":3891,"date":"2016-05-26T05:26:39","date_gmt":"2016-05-26T03:26:39","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=3891"},"modified":"2016-05-26T05:26:39","modified_gmt":"2016-05-26T03:26:39","slug":"wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-267","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-267\/","title":{"rendered":"Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle"},"content":{"rendered":"<p style=\"text-align: justify;\">Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n<div id=\"attachment_3892\" style=\"width: 838px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3892\" data-attachment-id=\"3892\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-267\/image-500\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/05\/image-36.png\" data-orig-size=\"828,302\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Wettervorhersage 26.05.2016\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/05\/image-36.png\" class=\"wp-image-3892 size-full\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/05\/image-36.png\" alt=\"Wettervorhersage 26.05.2016\" width=\"828\" height=\"302\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/05\/image-36.png 828w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/05\/image-36-300x109.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/05\/image-36-768x280.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a><p id=\"caption-attachment-3892\" class=\"wp-caption-text\">www.yr.no<\/p><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Heute zun\u00e4chst stark bew\u00f6lkt und \u00f6rtlich Schauer. Nachts trocken.<\/p>\n<p style=\"text-align: justify;\">Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Mit einer nordwestlichen Bodenstr\u00f6mung gelangt weiterhin feuchte Meeresluft von der Nordsee nach Sachsen-Anhalt.<\/p>\n<p style=\"text-align: justify;\">Bis Freitagfr\u00fch werden keine warnrelevanten Wettererscheinungen erwartet.<\/p>\n<p style=\"text-align: justify;\">Detaillierter Wetterablauf: Heute Fr\u00fch und am Vormittag ist es zun\u00e4chst noch stark bew\u00f6lkt, am Nachmittag lockert die Wolkendecke stellenweise auf und es gibt etwas Sonnenschein. Abgesehen von einzelnen Schauern im Norden bleibt es trocken. Bei schwachem Nordwind werden 17 bis 20, im Harz 13 bis 16 Grad erreicht. In der Nacht zum Freitag ist es zun\u00e4chst noch wolkig, die Wolken l\u00f6sen sich jedoch rasch auf und es wird meist gering bew\u00f6lkt sein. Dabei ist es niederschlagsfrei. Bei nur schwachem Wind aus n\u00f6rdlichen Richtungen k\u00fchlt die Luft auf 11 bis 9, im Harz bis 7 Grad ab.<\/p>\n<p style=\"text-align: justify;\">Am Freitag beginnt der Tag mit zeitweiligem Sonnenschein. Sp\u00e4ter bilden sich zahlreiche Quellwolken, die vor allem in der zweiten Tagesh\u00e4lfte f\u00fcr Schauer und Gewitter sorgen. \u00d6rtlich ist Starkregen zu erwarten. Nur in der Altmark besteht eine geringere Niederschlagsneigung. Die Temperatur steigt bei schwachem Nordwind auf 21 bis 23, im Harz auf 17 bis 21 Grad. In der Nacht zum Samstag ist es wolkig und niederschlagsfrei. Die Temperatur sinkt auf 12 bis 8 Grad. Der Wind weht schwach aus \u00f6stlichen Richtungen.<\/p>\n<p style=\"text-align: justify;\">Am Samstag beginnt der Tag mit Sonnenschein. Im Tagesverlauf bilden sich dann aber Quellwolken, die sich am Nachmittag und Abend zu teils kr\u00e4ftigen Schauern und Gewittern entwickeln. Die Temperatur erreicht 22 bis 24, im Harz 16 bis 22 Grad. Von Gewitterb\u00f6en abgesehen ist nur schwacher Wind aus uneinheitlichen Richtungen zu erwarten. In der Nacht zum Sonntag schw\u00e4cht sich die Schauer- und Gewittert\u00e4tigkeit bei meist noch starker Bew\u00f6lkung nur allm\u00e4hlich ab. Die Temperatur geht auf 15 bis 12, im Harz bis 10 Grad zur\u00fcck. Der schwache Wind dreht allm\u00e4hlich auf S\u00fcdost und frischt nur in Gewittern\u00e4he stark b\u00f6ig auf.<\/p>\n<p style=\"text-align: justify;\">Am Sonntag ist es zun\u00e4chst wolkig, sp\u00e4ter \u00fcberwiegend stark bew\u00f6lkt. Dabei werden sich im Tagesverlauf rasch Schauer und Gewitter bilden. Starke Entwicklungen mit Starkregen, B\u00f6en und kleink\u00f6rnigem Hagel sind m\u00f6glich. Es weht schwacher bis m\u00e4\u00dfiger, teils b\u00f6iger Wind aus Ost bis S\u00fcdost. Auf dem Brocken treten Sturmb\u00f6en auf. Die Maximalwerte erreichen 23 bis 27 Grad, im Harz 17 bis 22 Grad. In der Nacht zum Montag ist es meist stark bew\u00f6lkt, nur gelegentlich sind Auflockerungen vorhanden. Es regnet zeitweise leicht oder es treten noch Schauer oder Gewitter auf. Weiterhin ist Starkregen m\u00f6glich. Der Wind weht weiterhin aus Ost und im Mittel schwach, in B\u00f6en frisch. Auf dem Brocken treten Sturmb\u00f6en auf. Die Tiefstwerte liegen zwischen 17 bis 13 Grad, im Harz zwischen 15 und 12 Grad.<\/p>\n<p style=\"text-align: justify;\">Deutscher Wetterdienst, RWB Leipzig, Sebastian Schappert<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle Heute zun\u00e4chst stark bew\u00f6lkt und \u00f6rtlich Schauer. Nachts trocken. Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Mit einer nordwestlichen Bodenstr\u00f6mung gelangt weiterhin feuchte Meeresluft von der Nordsee nach Sachsen-Anhalt. Bis Freitagfr\u00fch werden keine warnrelevanten <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-267\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[39,5,95,38,96],"yst_prominent_words":[],"class_list":["post-3891","post","type-post","status-publish","format-standard","hentry","category-wetterblog","tag-brachwitz","tag-halle","tag-saalekreis","tag-wettervorhersage","tag-wettin-loebejuen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-10L","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/3891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=3891"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/3891\/revisions"}],"predecessor-version":[{"id":3893,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/3891\/revisions\/3893"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=3891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=3891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=3891"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=3891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}