{"id":473,"date":"2015-05-26T07:54:36","date_gmt":"2015-05-26T07:54:36","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=473"},"modified":"2015-05-26T07:54:37","modified_gmt":"2015-05-26T07:54:37","slug":"thema-des-tages-graeserpollen-auf-dem-vormarsch","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/thema-des-tages-graeserpollen-auf-dem-vormarsch\/","title":{"rendered":"Thema des Tages &#8211; Gr\u00e4serpollen auf dem Vormarsch"},"content":{"rendered":"<p>*Einen Tropfen auf den hei\u00dfen Stein in Form von Niederschl\u00e4gen durch Schauer und Gewitter gab es am gestrigen Pfingstmontag in einigen Teilen Deutschlands, insbesondere in der Mitte und im S\u00fcden. \u00d6rtlich konnten dabei zweistellige Regenmengen beobachtet werden, am meisten Regen fiel mit 31 Liter pro Quadratmeter auf dem Feldberg im Schwarzwald und am bayrischen Alpenrand in Hindelang-Unterjoch. Nach Norden und Osten hin waren die Niederschl\u00e4ge schw\u00e4cher ausgepr\u00e4gt, gebietsweise blieb es sogar wieder trocken. Einerseits ist durch die zum Teil anhaltende Trockenheit die Waldbrandgefahr in einigen Regionen Deutschlands weiterhin hoch (siehe auch www.dwd.de\/waldbrand), andererseits sind auch viele Pollen unterwegs. Aktuell sind dabei vor allem Gr\u00e4serpollen in der Luft. Die Schauer und Gewitter haben durch Auswaschung der Luftpartikel meist nur kurzzeitig eine Besserung gebracht.<\/p>\n<p>Die eigentliche Pollenflugsaison beginnt h\u00e4ufig schon im Januar (siehe dazu den Pollenflugkalendar der Stiftung Deutscher Pollenfluginformationsdienst, zu finden unter www.dwd.de\/tagesthema), manchmal sogar schon im Dezember. Unter g\u00fcnstigen Witterungsbedingungen sind dann erste Erlen- und Haselpollen unterwegs. Ende Januar schlie\u00dfen sich auch Pappel-, Weiden-, Eschen- und Eichenpollen an, wenn es das Wetter erlaubt. Im Februar kommen Hainbuchen- und Birkenpollen dazu, im M\u00e4rz steigen Buchen-, Kiefer- und Gr\u00e4serpollen ein. Ab April sind Spitzwegerich-, Roggen- und Brennnessel-, ab Mai Beifu\u00df- und ab Juni Ambrosiapollen (Taubenkrautpollen) m\u00f6glich.<\/p>\n<p>F\u00fcr die acht allergologisch wichtigsten Bl\u00fctenpollen gibt es beim Deutschen Wetterdienst Vorhersagen der Belastungsintensit\u00e4t durch den sogenannten Pollenflug-Gefahrenindex. Zu diesen acht wichtigsten Bl\u00fctenpollen z\u00e4hlen die Pollen der Hasel, Erle, Esche, Birke, Gr\u00e4ser, Roggen, Beifu\u00df und der Ambrosia. Etwa 95% der gesch\u00e4tzt rund 15 Millionen Pollenallergiker in Deutschland leiden beim Flug dieser Pollen. Vorhersagen sind unter www.dwd.de\/pollenflug abrufbar, die sich auch per E-Mail als Newsletter unter www.dwd.de\/newsletter (Stichpunkt &#8222;Pollenflug-Gefahrenindex&#8220;) abonnieren lassen.<\/p>\n<p>In den aktuellen Vorhersagen zeigt sich, passend zum im Pollenflugkalendar angegebenen Termin, dass die Hauptbl\u00fcte der Gr\u00e4ser begonnen hat. So wird f\u00fcr heute und morgen meist mit einer mittleren oder hohen Belastung durch Gr\u00e4serpollen gerechnet. Insbesondere am Oberrhein wird die h\u00f6chste Belastung erwartet, w\u00e4hrend sie an der \u00f6stlichen Nordseek\u00fcste am geringsten ist. Beim Roggen hat die Hauptbl\u00fcte, die \u00fcblicherweise f\u00fcr Ende Mai einzuplanen ist, noch nicht begonnen. So gibt es \u00fcberwiegend noch keine oder nur eine geringe Belastung, allenfalls am Oberrhein ist eine mittlere Belastung zu finden. Keine Belastung mehr tritt durch Birkenpollen auf, deren Saison vorbei ist. Auch Beifu\u00df- und Ambrosiapollen fliegen noch nicht, da ihre Saison in diesem Jahr noch nicht angefangen hat.<\/p>\n<p>In den n\u00e4chsten Tagen bleibt es leicht wechselhaft, wobei es heute und morgen zun\u00e4chst aber vielfach trocken ist. Ab Donnerstag stehen wieder vermehrt Niederschl\u00e4ge auf dem Zettel, auch am Wochenende sieht es nach Regen oder Gewitter aus. Das d\u00fcrfte den Pollenflug zumindest zeitweise hemmen. Zudem sprechen die bis zum Wochenende nur langsam ansteigenden Temperaturen ebenso gegen ein verst\u00e4rktes Wachstum der Natur.<\/p>\n<p>Dipl.-Met. Simon Trippler Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 26.05.2015 Copyright (c) Deutscher Wetterdienst<\/p>\n<p>&nbsp;<\/p>\n<h4>Die Themen des Tagen finden sie <a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/?page_id=135\" target=\"_blank\">hier<\/a>\u00a0unter Informationen.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>*Einen Tropfen auf den hei\u00dfen Stein in Form von Niederschl\u00e4gen durch Schauer und Gewitter gab es am gestrigen Pfingstmontag in einigen Teilen Deutschlands, insbesondere in der Mitte und im S\u00fcden. \u00d6rtlich konnten dabei zweistellige Regenmengen beobachtet werden, am meisten Regen <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/thema-des-tages-graeserpollen-auf-dem-vormarsch\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[47,46,45,4],"yst_prominent_words":[6940,6937,2135,1216,2256,2171,3267,6938,6698,2169,3977,2019,6939,3846,4419,3961,2842,3544,1513,6936],"class_list":["post-473","post","type-post","status-publish","format-standard","hentry","category-wetterblog","tag-heuschnupfen","tag-pollen","tag-thema-des-tages","tag-wetter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-7D","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/473\/revisions"}],"predecessor-version":[{"id":474,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/473\/revisions\/474"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=473"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}