{"id":5834,"date":"2016-12-14T16:55:30","date_gmt":"2016-12-14T14:55:30","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=5834"},"modified":"2016-12-14T16:55:30","modified_gmt":"2016-12-14T14:55:30","slug":"schneesuche","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/schneesuche\/","title":{"rendered":"Schneesuche"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Schneesuche<\/h2>\n<p style=\"text-align: justify;\">\nViel Grau und wenig Schnee bietet der Winter bisher in Deutschland. Mit der aktuellen Schneesituation in den Alpen besch\u00e4ftigt sich heute das Thema des Tages.<\/p>\n<p style=\"text-align: justify;\">Wer heute Morgen (14.12.) auf die Homepage des DWD oder in die WarnWetter-App geschaut hat, konnte zumindest Ans\u00e4tze von winterlichem Wetter erhaschen. Warnungen vor leichtem Frost im S\u00fcden und S\u00fcdosten lie\u00dfen sich finden, und s\u00fcdlich der Donau sorgte leichter Regen auf gefrorenen B\u00f6den f\u00fcr Glatteis.<\/p>\n<p style=\"text-align: justify;\">Dieses vor\u00fcbergehende winterliche Intermezzo kann aber nicht dar\u00fcber hinwegt\u00e4uschen, dass sich der Winter bisher vornehm zur\u00fcckgehalten und allenfalls kurze Gastspiele gegeben hat. Wer den Winter, respektive den Schnee sucht, muss schon h\u00f6her hinaus, wie der Blick auf das beigef\u00fcgte Satellitenbild vom gestrigen Dienstag zeigt. Zu sehen sind dort u.a. die Alpen, bei denen einerseits die Gipfel schneebedeckt sind, sich andererseits aber die T\u00e4ler deutlich abzeichnen.<\/p>\n<p style=\"text-align: justify;\">Eine der schneebedeckten Regionen sind die Hohen Tauern als Teil des Alpenhauptkammes. In der Abbildung weist der k\u00fcrzere &#8222;Alpenpfeil&#8220; genau in ihre Richtung. Sie heben sich als besonders heller Streifen von der Umgebung ab, die dortige Station &#8222;Alpinzentrum Rudolfsh\u00fctte&#8220; auf 2317 m H\u00f6he meldete heute Morgen 74 cm Schnee, der nahe gelegene, 3105 m hohe Sonnblick sogar 137 cm. Sehr hell und damit schneereich pr\u00e4sentieren sich auch die Alpen im Grenzgebiet von Frankreich und Italien. Sie erinnern sich vielleicht: Rund um den L\u00f6wengolf und den Golf von Genua kam es vor etwa drei Wochen zu sehr kr\u00e4ftigen Niederschl\u00e4gen. Und diese sind in den Hochlagen als Schnee gefallen, was jetzt noch im Satellitenbild zu erkennen ist. Und in Deutschland? Allenfalls einige sch\u00fcchterne helle Flecken lassen sich in den deutschen Alpen ausmachen &#8211; bei den Liftbetreibern und in den Tourismusb\u00fcros d\u00fcrften zumindest bez\u00fcglich des Schnees Wunsch und Wirklichkeit deutlich auseinanderklaffen.<\/p>\n<p style=\"text-align: justify;\">Dieses Dilemma kennt man bei unseren s\u00fcdlichen Nachbarn aber auch. In der Schweiz ist beispielsweise das Rhonetal schneefrei, und in \u00d6sterreich erkennt man n\u00f6rdlich der Hohen Tauern das Salzachtal und das Inntal als dunkle Streifen im Satellitenbild. Bei einer sehr (wirklich sehr!) groben Absch\u00e4tzung der Schneegrenze kommt man \u00fcbrigens auf etwa 800 bis 1000 Meter. So melden Garmisch-Partenkirchen (719 m), das S\u00fcdtiroler St\u00e4dtchen Sterzing (948 m) und das \u00f6sterreichische Bad Gastein auf 1002 m H\u00f6he alle etwa 2 cm Schnee. Das reicht f\u00fcr winterliche Tagtr\u00e4ume, f\u00fcr Wintersport reicht es aber nicht. Es sei denn, es wurde mit Schneekanonen nachgeholfen, und daf\u00fcr waren die Bedingungen in der letzten Zeit sehr gut.<\/p>\n<p style=\"text-align: justify;\">Immerhin: Wer sich in den Alpen mit winterlichen Tagtr\u00e4umen begn\u00fcgen musste, konnte das oftmals bei strahlendem Sonnenschein tun. Schlie\u00dflich ist der Alpenbogen nur deshalb so sch\u00f6n zu erkennen, weil er nicht von Wolken verdeckt wird. Da kann man in vielen neblig-grau-tr\u00fcben Ecken Deutschlands schon neidisch werden.<\/p>\n<p style=\"text-align: justify;\">Oder vielleicht an Leidensgenossen denken. Diese sind in unserem Bild in der Poebene zu erkennen (also, genau genommen sind sie eben nicht zu erkennen). Die Poebene pr\u00e4sentierte sich gestern n\u00e4mlich unter einer dichten Nebeldecke, die Sonne hatte von Ferrara im Osten \u00fcber Piacenza bis nach Asti im Westen keine Chance. Das ist \u00e4hnlich wie in der Norddeutschen Tiefebene.<\/p>\n<p style=\"text-align: justify;\">Aber: Von Asti ist man schnell in den schneebedeckten und auch heute wieder sonnenverw\u00f6hnten Seealpen.<\/p>\n<p style=\"text-align: justify;\">Dipl.-Met. Martin Jonas<\/p>\n<p style=\"text-align: justify;\">Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 14.12.2016<\/p>\n<p style=\"text-align: justify;\">Copyright (c) Deutscher Wetterdienst<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5835\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/schneesuche\/img_1329\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329.png\" data-orig-size=\"863,614\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Schneesuche\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329.png\" class=\"alignnone size-full wp-image-5835\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329.png\" alt=\"\" width=\"863\" height=\"614\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329.png 863w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329-300x213.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329-768x546.png 768w\" sizes=\"auto, (max-width: 863px) 100vw, 863px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schneesuche Viel Grau und wenig Schnee bietet der Winter bisher in Deutschland. Mit der aktuellen Schneesituation in den Alpen besch\u00e4ftigt sich heute das Thema des Tages. Wer heute Morgen (14.12.) auf die Homepage des DWD oder in die WarnWetter-App geschaut <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/schneesuche\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5835,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[304,92,297],"yst_prominent_words":[],"class_list":["post-5834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-frost","tag-schnee","tag-winter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2016\/12\/IMG_1329.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-1w6","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/5834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=5834"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/5834\/revisions"}],"predecessor-version":[{"id":5836,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/5834\/revisions\/5836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/5835"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=5834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5834"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=5834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}