{"id":6648,"date":"2017-03-15T12:36:21","date_gmt":"2017-03-15T10:36:21","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=6648"},"modified":"2017-03-15T12:36:21","modified_gmt":"2017-03-15T10:36:21","slug":"maerz-2017-bisher-sehr-mild-und-etwas-zu-nass","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/maerz-2017-bisher-sehr-mild-und-etwas-zu-nass\/","title":{"rendered":"M\u00e4rz 2017 &#8211; Bisher sehr mild und etwas zu nass"},"content":{"rendered":"<h2 style=\"text-align: justify;\">M\u00e4rz 2017 &#8211; Bisher sehr mild und etwas zu nass<\/h2>\n<p style=\"text-align: justify;\">\nDie erste M\u00e4rzh\u00e4lfte ist vorbei. Daher ist es Zeit, eine kurze Zwischenbilanz zu ziehen: H\u00e4ufige Westwetterlagen mit milder Meeresluft sorgten f\u00fcr einen etwas zu nassen und fast schon deutlich zu warmen M\u00e4rz.<\/p>\n<p style=\"text-align: justify;\">Die erste M\u00e4rzh\u00e4lfte ist vorbei. Daher ist es Zeit, eine kurze Zwischenbilanz zu ziehen. Bisher war der M\u00e4rz mit einer Abweichung von etwa 2,3 Grad vom langj\u00e4hrigen Mittel schon deutlich zu warm. Vom Niederschlag her gestaltete sich die erste M\u00e4rzh\u00e4lfte etwas zu nass (etwa 110 % des sonst \u00fcblichen Niederschlags). W\u00e4hrend es im Nordosten zu trocken aber sonnenscheinarm blieb, hat der S\u00fcdwesten \u00fcberdurchschnittlich viel Niederschlag abbekommen.<\/p>\n<p style=\"text-align: justify;\">Ursache f\u00fcr die milde und niederschlagsreiche Witterung war eine Westwetterlage, bei der Tiefdruckgebiete in schneller Abfolge vom Atlantik kommend \u00fcber Skandinavien zogen und Deutschland mit ihren Ausl\u00e4ufern beeinflussten. Dabei wurde abwechselnd milde Subtropikluft und erw\u00e4rmte polare Meeresluft herangef\u00fchrt. So blieben gr\u00f6\u00dfere Wintereinbr\u00fcche bis in tiefe Lagen aus. Nur in den Gipfellagen der Mittelgebirge und in den Alpen reichte es zeitweise f\u00fcr Schnee. Meist herrschte dort aber auch leichtes Tauwetter, sodass die Schneeh\u00f6he f\u00fcr die Jahreszeit ziemlich gering ist. Eine ausgepr\u00e4gte F\u00f6hnlage zu Beginn des Monats war in den Alpen ein regelrechter &#8222;Schneefresser&#8220;. Erst in den vergangenen Tagen setzte sich schwacher Hochdruckeinfluss durch, der am Wochenende zumindest im Osten Deutschlands kurzzeitig kontinentale Kaltluft herangef\u00fchrt hat. F\u00fcr mehr als leichte bis m\u00e4\u00dfige Nachtfr\u00f6ste hat diese aber nicht gereicht, da es auch in Osteuropa und Sibirien f\u00fcr die Jahreszeit teilweise sogar deutlich zu warm war.<\/p>\n<p style=\"text-align: justify;\">Da im M\u00e4rz im Norden und in Sibirien h\u00e4ufig noch Kaltluft liegt, sich im S\u00fcden aber das Land durch den schon relativ hohen Sonnenstand erw\u00e4rmt hat, sind im M\u00e4rz ziemlich Extreme in den Temperaturen m\u00f6glich. Diese blieben in diesem M\u00e4rz jedoch bisher aus. Wie extrem sich das Wetter im M\u00e4rz in beide Richtungen entwickeln kann, zeigen die aufeinanderfolgenden Jahre 2013 und 2014. Im \u00e4u\u00dferst strengen M\u00e4rzwinter 2013 sorgte der kontinuierliche Zustrom sibirischer Kaltluft f\u00fcr eine Temperaturabweichung von -3,1 Grad. Dauerfrost, teilweise strenge Nachtfr\u00f6ste bis unter -20 Grad und Schneef\u00e4lle waren an der Tagesordnung. Teilweise konnte sich auch im Flachland bis Ende des Monats eine geschlossene Schneedecke halten. Dass es auch anders geht zeigte dann der M\u00e4rz 2014. Hochdrucklagen mit Zufuhr subtropischer Luftmassen sorgten oftmals f\u00fcr H\u00f6chstwerte von verbreitet \u00fcber 20 Grad. Auch nachts blieb es meist frostfrei. Richtige Kaltlufteinbr\u00fcche blieben aus, sodass dieser M\u00e4rz um 3,5 Grad zu warm ausfiel.<\/p>\n<p style=\"text-align: justify;\">An diese Temperaturen werden wir in den n\u00e4chsten Tagen wohl nicht heran kommen. Denn nach der Hochdrucklage setzt sich wieder die Westwetterlage mit kurzen Wechseln zwischen subtropischer Luft und erw\u00e4rmter Polarluft durch. So bleibt es in den n\u00e4chsten Tagen feucht mit Temperaturen auf einem f\u00fcr die Jahreszeit etwas zu warmen Niveau. Wie lange diese Westwetterlage in der neuen Woche noch anh\u00e4lt, ist noch unsicher. Dass der M\u00e4rz in diesem Jahr nochmal zu kalt ausf\u00e4llt, ist allerdings \u00e4u\u00dferst unwahrscheinlich.<\/p>\n<p style=\"text-align: justify;\">Dipl.-Met. Christian Herold<\/p>\n<p style=\"text-align: justify;\">Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 15.03.2017<\/p>\n<p style=\"text-align: justify;\">Copyright (c) Deutscher Wetterdienst<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e4rz 2017 &#8211; Bisher sehr mild und etwas zu nass Die erste M\u00e4rzh\u00e4lfte ist vorbei. Daher ist es Zeit, eine kurze Zwischenbilanz zu ziehen: H\u00e4ufige Westwetterlagen mit milder Meeresluft sorgten f\u00fcr einen etwas zu nassen und fast schon deutlich zu <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/maerz-2017-bisher-sehr-mild-und-etwas-zu-nass\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":6650,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[1352,128,679,3571],"yst_prominent_words":[1936,2229,1216,3562,3558,3563,3081,2054,3564,3559,3565,3560,3569,3570,1451,3566,3035,3568,3567,3561],"class_list":["post-6648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-1352","tag-maerz","tag-nass","tag-warm"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3575.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-1Je","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/6648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6648"}],"version-history":[{"count":2,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/6648\/revisions"}],"predecessor-version":[{"id":6651,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/6648\/revisions\/6651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/6650"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=6648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=6648"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=6648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}