{"id":6672,"date":"2017-03-18T15:22:00","date_gmt":"2017-03-18T13:22:00","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=6672"},"modified":"2017-03-18T15:22:00","modified_gmt":"2017-03-18T13:22:00","slug":"der-erstfruehling-ist-da","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/der-erstfruehling-ist-da\/","title":{"rendered":"Der Erstfr\u00fchling ist da"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Der Erstfr\u00fchling ist da<\/h2>\n<p style=\"text-align: justify;\">\nMit der Bl\u00fcte der Forsythie beginnt der Erstfr\u00fchling, der sich normalerweise von Mitte M\u00e4rz bis Ende April erstreckt.<\/p>\n<p style=\"text-align: justify;\">In der Lehre von den periodisch wiederkehrenden Abl\u00e4ufen in der Tier- und Pflanzenwelt, der Ph\u00e4nologie, gibt es die Jahreszeiten Fr\u00fchjahr, Sommer, Herbst und Winter. Bis auf den Winter werden sie in jeweils drei Perioden unterteilt, sodass es insgesamt 3*3+1, also 10 ph\u00e4nologische Jahreszeiten gibt. Der Fr\u00fchling wird eingeteilt in Vor-, Erst und Vollfr\u00fchling. Im Gegensatz zum Kalender, bei dem der Sonnenstand ziemlich periodisch den Beginn der einzelnen Jahreszeiten bestimmt, h\u00e4ngen die ph\u00e4nologischen Jahreszeiten von Bl\u00fchbeginn, Beginn der Blattentfaltung, Reifegrad und schlie\u00dflich im Herbst vom Laubfall ab. Vom Vorfr\u00fchling hatten wir im Thema des Tages vom 12.02.2017 geschrieben. Nun kommt er langsam zu seinem Ende, denn die f\u00fcr die Definition des Erstfr\u00fchlings bestimmende Pflanze, die Forsythie, hat zu bl\u00fchen begonnen, insbesondere am Oberrhein und n\u00f6rdlich des Rheinischen Schiefergebirges, wo etwa ab dem 10. M\u00e4rz die Bl\u00fcte einsetzte. Deutschlandweit betrachtet liegt der Vorfr\u00fchling normalerweise in der Zeit von Mitte M\u00e4rz bis Ende April.<\/p>\n<p style=\"text-align: justify;\">Wie wir im Thema des Tages \u00fcber den Erstfr\u00fchling lesen konnten, war die Natur damals wegen des insbesondere nach S\u00fcden hin kalten Januars vergleichsweise sp\u00e4t dran. Wie sieht es nun nach den vielen milden Tagen aus? Bis zum 20. Februar hatte die Natur trotzdem kaum aufgeholt, am Oberrhein hat sich die milde Witterung inzwischen tats\u00e4chlich ausgewirkt: Das versp\u00e4tete Pflanzenwachstum hat inzwischen den Normalwert erreicht, der dort den Bl\u00fchbeginn der Forsythie auf die Zeit zwischen dem 1. und 20. M\u00e4rz angibt. (Die Extreme liegen um den 8. Februar bzw. 5. April). Im Norden war der Januar eher mild und da k\u00f6nnte man auf einen Erstfr\u00fchling fr\u00fcher als \u00fcblich hoffen. Aber von der Hamburger Lombartsbr\u00fccke, f\u00fcr die eine Zeitreihe seit 1945 vorliegt, gab es bis heute noch keine Meldung. Der Mittelwert f\u00fcr den Bl\u00fchbeginn liegt dort aber auch erst am 24. M\u00e4rz, wobei dort als fr\u00fchester bzw. sp\u00e4tester Bl\u00fchbeginn der 15.Februar bzw. 25. April aufgezeichnet wurden. Im Rahmen der Diskussion zur Klima\u00e4nderung kann man sich auch den Trend f\u00fcr den Beginn der ph\u00e4nologischen Jahreszeiten anschauen. Da stellen wir in der entsprechenden Statistik f\u00fcr den Oberrhein fest (s. Abbildung), dass sich der mittlere Bl\u00fchbeginn der Forsythie gegen\u00fcber 1950 um etwa zw\u00f6lf Tage, also knapp zwei Wochen nach vorne verschoben hat. Was die ph\u00e4nologischen Phasen der anderen Pflanzen wie z.B. die Hasel betrifft, so haben auch sie weitgehend den R\u00fcckstand zu Beginn des Vorfr\u00fchlings wettgemacht.<\/p>\n<p style=\"text-align: justify;\">Dipl.-Met. Christoph Hartmann<\/p>\n<p style=\"text-align: justify;\">Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 18.03.2017<\/p>\n<p style=\"text-align: justify;\">Copyright (c) Deutscher Wetterdienst<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6674\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/der-erstfruehling-ist-da\/img_3646\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646.jpg\" data-orig-size=\"600,370\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Der Erstfr\u00fchling ist da\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646.jpg\" class=\"alignnone size-full wp-image-6674\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646.jpg\" alt=\"\" width=\"600\" height=\"370\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646.jpg 600w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646-300x185.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Erstfr\u00fchling ist da Mit der Bl\u00fcte der Forsythie beginnt der Erstfr\u00fchling, der sich normalerweise von Mitte M\u00e4rz bis Ende April erstreckt. In der Lehre von den periodisch wiederkehrenden Abl\u00e4ufen in der Tier- und Pflanzenwelt, der Ph\u00e4nologie, gibt es die <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/der-erstfruehling-ist-da\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":6674,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[129,3627,3625,3626,70,128],"yst_prominent_words":[3458,2855,3621,3617,2856,1216,2447,3618,3622,3623,3620,3616,3615,2849,2846,3614,3613,3624,3293,3619],"class_list":["post-6672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-april","tag-bluete","tag-erstfruehling","tag-forsythie","tag-fruehling","tag-maerz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/03\/IMG_3646.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-1JC","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/6672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6672"}],"version-history":[{"count":2,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/6672\/revisions"}],"predecessor-version":[{"id":6675,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/6672\/revisions\/6675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/6674"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=6672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=6672"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=6672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}