{"id":7546,"date":"2017-08-01T05:17:09","date_gmt":"2017-08-01T03:17:09","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=7546"},"modified":"2017-08-01T05:17:09","modified_gmt":"2017-08-01T03:17:09","slug":"wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-670","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-670\/","title":{"rendered":"Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle"},"content":{"rendered":"<p style=\"text-align: justify;\">Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n<div id=\"attachment_7556\" style=\"width: 838px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7556\" data-attachment-id=\"7556\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-670\/img_6966\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_6966.png\" data-orig-size=\"828,302\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_6966\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_6966.png\" class=\"wp-image-7556 size-full\" title=\"Beidersee, brachwitz, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, Gimritz, Gottgau, Halle, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, Rothenburg, saalekreis, Salzm\u00fcnde, Schiepzig, Schlettau, Taupunkt, Temperatur, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_6966.png\" alt=\"\" width=\"828\" height=\"302\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_6966.png 828w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_6966-300x109.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/IMG_6966-768x280.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a><p id=\"caption-attachment-7556\" class=\"wp-caption-text\">www.yr.no (Klicke auf das Bild)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>In der Fr\u00fch schauerartiger, teils gewittriger Regen. \u00d6rtlich UNWETTER. Tags\u00fcber dann sonnig und hei\u00df, in der zweiten Tagesh\u00e4lfte bis in die Nacht erneut UNWETTER.<\/p>\n<p>Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Im Einflussbereich eines Nordatlantiktiefs wird mit einer s\u00fcdwestlichen Str\u00f6mung sehr warme bis hei\u00dfe Luft nach Sachsen-Anhalt herangef\u00fchrt.<\/p>\n<p>Heute Fr\u00fch kommt es zu schauerartigem Regen, der mit starken, teils schweren Gewittern durchsetzt ist. Es besteht die Gefahr von Starkregen zwischen 15 und 25 l\/qm in kurzer Zeit, Sturmb\u00f6en zwischen 65 und 85 km\/h (Bft 8 bis 9) und Hagel. Stellenweise ist auch Starkregen mit Mengen zwischen 20 und 35 l\/qm in 6 Stunden wahrscheinlich. \u00d6rtlich sind auch unwetterartige Entwicklungen mit heftigem Starkregen von \u00fcber 25 l\/qm in kurzer Zeit, schweren Sturmb\u00f6en bis 100 km\/h (Bft 10) sowie Hagel nicht ausgeschlossen. Am Vormittag ziehen die Niederschl\u00e4ge dann vor\u00fcbergehend ab. Dann werden zun\u00e4chst keine warnw\u00fcrdigen Wettererscheinungen erwartet. Im Laufe des Nachmittags steigt das Gewitterrisiko von Westen her wieder an und schwere Gewitter mit erh\u00f6htem Unwetterpotential durch heftigen Starkregen bis 40 l\/qm in einer Stunde und gr\u00f6\u00dferen Hagel um 4 cm sind wahrscheinlich. \u00d6rtlich sind orkanartige B\u00f6en um 110 km\/h (Bft 11) gering wahrscheinlich. Ganz vereinzelt kann ein Tornado nicht ausgeschlossen werden. Zudem wird tags\u00fcber gebietsweise eine starke W\u00e4rmebelastung erwartet.<\/p>\n<p>In der Nacht zum Mittwoch muss mit weiteren teils schweren Gewittern bis in den Unwetterbereich gerechnet werden, die im Laufe der Nacht dann s\u00fcdostw\u00e4rts abziehen.<\/p>\n<p>Detaillierter Wetterablauf: Heute Fr\u00fch und am Vormittag muss besonders in der Mitte und im S\u00fcden noch mit schauerartigem Regen, der teils mit Gewitter durchsetzt ist, gerechnet werden. Starkregen ist dort wahrscheinlich. In den \u00fcbrigen Regionen beginnt der Tag wechselnd bew\u00f6lkt und abgesehen von einzelnen Schauern oder Gewittern niederschlagsfrei. Nachmittags wird es dann in den \u00f6stlichen Landesteilen heiter und zun\u00e4chst noch trocken sein, w\u00e4hrend von Westen erneut starke, teils schwere Gewitter mit erh\u00f6htem Unwetterrisiko auftreten. In deren Umgebung sind heftiger Starkregen, Orkanb\u00f6en und gr\u00f6\u00dferer Hagel zu erwarten. Auch einzelne Tornados k\u00f6nnen nicht ganz ausgeschlossen werden. Die Temperatur steigt von Nord nach S\u00fcd auf 27 bis 33, im Harz auf 22 bis 29 Grad. Es herrscht im S\u00fcden und Osten eine starke W\u00e4rmebelastung. Abseits von Gewittern weht nur schwacher Wind aus Ost bis Nordost. In der Nacht zum Mittwoch kommt es zun\u00e4chst noch zu Schauern und teils unwetterartigen Gewittern, die bis etwa Mitternacht ostw\u00e4rts abziehen. Es lockert nachfolgend auf und bleibt trocken. Die Tiefstwerte liegen zwischen 19 und 16, im Harz zwischen 16 und 13 Grad. Der S\u00fcdwest- bis Westwind weht abgesehen von Gewitterb\u00f6en nur schwach.<\/p>\n<p>Am Mittwoch ist es teils heiter, teils wolkig. \u00d6rtlich entwickeln sich im Tagesverlauf Schauer, vereinzelt auch Gewitter. Bei schwachem westlichem Wind werden Maxima zwischen 26 und 28, im Harz zwischen 19 und 26 Grad erreicht. In der Nacht zum Donnerstag verdichtet sich die Bew\u00f6lkung z\u00f6gerlich und gegen Morgen kommt von Westen her schauerartiger Regen auf. Vereinzelt sind auch Gewitter eingelagert. Die Luft k\u00fchlt auf 19 bis 15 Grad ab. Der S\u00fcdostwind weht schwach.<\/p>\n<p>Am Donnerstag \u00fcberqueren die schauerartigen und gewittrigen Regenf\u00e4lle die Region von West nach Ost. Nachfolgend lockert die Wolkendecke auf und die Sonne kommt zum Vorschein. Der Wind weht m\u00e4\u00dfig und dreht von S\u00fcdost auf S\u00fcdwest. Die Tagesh\u00f6chstwerte liegen zwischen 27 und 29, im Harz zwischen 20 und 27 Grad. In der Nacht zum Freitag wird es bei stark bew\u00f6lktem Himmel meist niederschlagsfrei sein. Die Minima liegen bei schwachem bis m\u00e4\u00dfigem S\u00fcdwestwind zwischen 19 und 16, im Harz zwischen 16 und 13 Grad.<\/p>\n<p>Am Freitag wechseln sich l\u00e4ngere bew\u00f6lkte mit kurzen sonnigen Abschnitten ab. \u00d6rtlich kommt es zu Schauern. Bei m\u00e4\u00dfigem und b\u00f6igem S\u00fcdwestwind wird die Luft auf 25 bis 28, im Harz auf 17 bis 25 Grad erw\u00e4rmt. In der Nacht zum Samstag ziehen bei wechselnder Bew\u00f6lkung einzelne Schauer und Gewitter vor\u00fcber. Die Tiefstwerte liegen zwischen 16 und 14, im Harz zwischen 14 und 11 Grad. Der S\u00fcdwestwind weht schwach.<\/p>\n<p>Deutscher Wetterdienst, RWB Leipzig, Sebastian Schappert<\/p>\n<h3>Mehr Wetter?<\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"e2wCbjyC3O\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/\">Wettervorhersage<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettervorhersage&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/embed\/#?secret=2JNDODQEjv#?secret=e2wCbjyC3O\" data-secret=\"e2wCbjyC3O\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"5DuYiU4hQF\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/\">Wetterwarnungen<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wetterwarnungen&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/embed\/#?secret=1CsSNmeN6c#?secret=5DuYiU4hQF\" data-secret=\"5DuYiU4hQF\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"PpPB3B6p1g\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/\">Wettercam<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettercam&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/embed\/#?secret=ireSGHVp9n#?secret=PpPB3B6p1g\" data-secret=\"PpPB3B6p1g\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wettervorhersage Brachwitz, Wettin-L\u00f6bej\u00fcn, Saalekreis, Halle &nbsp; In der Fr\u00fch schauerartiger, teils gewittriger Regen. \u00d6rtlich UNWETTER. Tags\u00fcber dann sonnig und hei\u00df, in der zweiten Tagesh\u00e4lfte bis in die Nacht erneut UNWETTER. Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden: Im Einflussbereich <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wettervorhersage-brachwitz-wettin-loebejuen-saalekreis-halle-670\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[4859,39,4875,4870,4869,4881,4885,4882,4868,4884,4860,4887,5,4883,4873,4872,44,4878,487,4874,4877,4879,4876,63,462,95,4871,4880,4886,1006,231,708,4,94,38,43,96,113],"yst_prominent_words":[5532,5525,5533,5528,5531,5524,5534,1683,1793,5530,5051,5526,1120,2468,5527,5529,2027,1792,1564,2028],"class_list":["post-7546","post","type-post","status-publish","format-standard","hentry","category-wetterblog","tag-beidersee","tag-brachwitz","tag-deutleben","tag-dobis","tag-doeblitz","tag-domnitz","tag-dornitz","tag-doesel","tag-friedrichschwerz","tag-garsena","tag-gimritz","tag-gottgau","tag-halle","tag-kloschwitz","tag-lettewitz","tag-lettin","tag-loebejuen","tag-merbitz","tag-morl","tag-muecheln","tag-nauendorf","tag-neuragozy","tag-neutz-lettewitz","tag-niederschlag","tag-rothenburg","tag-saalekreis","tag-salzmuende","tag-schiepzig","tag-schlettau","tag-taupunkt","tag-temperatur","tag-vorhersage","tag-wetter","tag-wetterbericht","tag-wettervorhersage","tag-wettin","tag-wettin-loebejuen","tag-wind"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-1XI","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/7546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=7546"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/7546\/revisions"}],"predecessor-version":[{"id":7557,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/7546\/revisions\/7557"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=7546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=7546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=7546"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=7546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}