{"id":7631,"date":"2017-08-15T17:21:40","date_gmt":"2017-08-15T15:21:40","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=7631"},"modified":"2017-08-15T17:21:40","modified_gmt":"2017-08-15T15:21:40","slug":"gewitter-mit-unwetterpotential-15-08-2017","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-mit-unwetterpotential-15-08-2017\/","title":{"rendered":"Gewitter mit Unwetterpotential 15.08.2017"},"content":{"rendered":"<h2>Gewitter mit Unwetterpotential 15.08.2017<\/h2>\n<p>Uhrzeit: 17:15<\/p>\n<p>Schw\u00fcl und hei\u00df ist es. Das bedeutet jede Menge Energie f\u00fcr Gewitter. Heute Nachmittag hat ein kr\u00e4ftiger Downburst in Frankfurt am Main f\u00fcr ein Chaos gesorgt. Nun ist die Gewitterlinie auf dem Weg zu uns. Sie wird uns erst sp\u00e4t aus S\u00fcdwesten erreichen, was eventuell f\u00fcr eine Abschw\u00e4chung spricht. Mal sehen&#8230;<\/p>\n<p>Passt auf euch auf.<\/p>\n<h3>Wetterwarnung<\/h3>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20729680_1741337112591845_5552365401900922765_n.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7662\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-mit-unwetterpotential-15-08-2017\/20729680_1741337112591845_5552365401900922765_n\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20729680_1741337112591845_5552365401900922765_n.png\" data-orig-size=\"702,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gewitter mit Unwetterpotential 15.08.2017\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20729680_1741337112591845_5552365401900922765_n.png\" class=\"alignnone wp-image-7662 size-full\" title=\"Beidersee, brachwitz, dauerregen, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, gewitter, Gimritz, Gottgau, hagel, Halle, halle saale, H\u00e4ndel, Heide-Nord, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, M\u00f6derau, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, orkanb\u00f6en, Rothenburg, saalekreis, Sachen-Anhalt, Salzm\u00fcnde, Schiepzig, Schlettau, Sennewitz, starkregen, Taupunkt, Temperatur, Trotha, unwetter, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20729680_1741337112591845_5552365401900922765_n.png\" alt=\"\" width=\"702\" height=\"960\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20729680_1741337112591845_5552365401900922765_n.png 702w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20729680_1741337112591845_5552365401900922765_n-219x300.png 219w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/a> <a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o.png\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7663\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-mit-unwetterpotential-15-08-2017\/20785815_1458767364188915_2320571134451825359_o\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o.png\" data-orig-size=\"1280,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gewitter mit Unwetterpotential 15.08.2017\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o-1024x576.png\" class=\"alignnone wp-image-7663 size-full\" title=\"Beidersee, brachwitz, dauerregen, Deutleben, Dobis, D\u00f6blitz, Domnitz, Dornitz, D\u00f6sel, Friedrichschwerz, Garsena, gewitter, Gimritz, Gottgau, hagel, Halle, halle saale, H\u00e4ndel, Heide-Nord, Kloschwitz, Lettewitz, Lettin, l\u00f6bej\u00fcn, Merbitz, M\u00f6derau, morl, M\u00fccheln, Nauendorf, Neuragozy, Neutz-Lettewitz, niederschlag, orkanb\u00f6en, Rothenburg, saalekreis, Sachen-Anhalt, Salzm\u00fcnde, Schiepzig, Schlettau, Sennewitz, starkregen, Taupunkt, Temperatur, Trotha, unwetter, vorhersage, Wetter, wetterbericht, wettervorhersage, wettin, wettin-l\u00f6bej\u00fcn, wind\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o.png\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o.png 1280w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o-300x169.png 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o-768x432.png 768w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o-1024x576.png 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">\u00a0WARNLAGEBERICHT f\u00fcr Sachsen-Anhalt<\/h2>\n<p>ausgegeben vom Deutschen Wetterdienst am Dienstag, 15.08.2017, 16:33 Uhr<\/p>\n<p>Abends und in der Nacht Schauer und Gewitter mit Unwetterpotential. Am Mittwoch freundlich und etwas k\u00fchler.<\/p>\n<p>Entwicklung der Wetter- und Warnlage f\u00fcr die n\u00e4chsten 24 Stunden bis Mittwoch, 16.08.2017, 16 Uhr:<\/p>\n<p>Das bisher wetterbestimmende Hoch zieht allm\u00e4hlich nach Osten ab und von Westen her \u00fcberquert der Ausl\u00e4ufer eines Tiefs \u00fcber Skandinavien Sachsen-Anhalt in der Nacht. Die r\u00fcckseitig einflie\u00dfende etwas k\u00fchlere Meeresluft ger\u00e4t am Mittwoch unter Zwischenhocheinfluss.<\/p>\n<p>Ab den heutigen Abendstunden entwickeln sich westlich von Elbe und Saale Gewitter, die \u00f6rtlich mit Sturmb\u00f6en bis 85 km\/h (Bft 9), Starkregen um 20 l\/qm in einer Stunde und kleink\u00f6rnigem Hagel verbunden sind. In der Nacht zum Mittwoch breiten sich diese nach Osten aus. Dabei besteht infolge von heftigem Starkregen mit mehr als 25 l\/qm in einer Stunde und gr\u00f6\u00dferem Hagel Unwettergefahr. Am Mittwochmorgen ziehen die Niederschl\u00e4ge nach Osten ab. Danach werden keine warnrelevanten Wettererscheinungen mehr erwartet.<\/p>\n<p>Deutscher Wetterdienst, RWB Leipzig, Thomas Hain<\/p>\n<p>&nbsp;<\/p>\n<h2>Unwetter-Video DWD<\/h2>\n<p>n.v.<\/p>\n<div>\n<h3>Synoptische \u00dcbersicht<\/h3>\n<p>Heute von Westen her kr\u00e4ftige Gewitter, teils unwetterartig. In der Nacht Verlagerung der Gewitter nach Osten. Morgen vor allem am Alpenrand Gewitter, unwetterartige Entwicklungen nicht ausgeschlossen.<\/p>\n<p>Synoptische Entwicklung bis Donnerstag 24 UTC<\/p>\n<p>Dienstag&#8230; liegt Deutschland auf der Vorderseite eines langwelligen Troges, der sich um die Mittagszeit \u00fcber den Britischen Inseln und Frankreich befindet und wir kommen heute auf dessen diffluente Vorderseite. Weiterhin greift heute im Tagesverlauf das Frontensystem eines Randtiefs \u00fcber der n\u00f6rdlichen Nordsee auf uns \u00fcber, zun\u00e4chst mit einer Warmfront und am Nachmittag und Abend einer Kaltfront. Diese schlie\u00dft auch eine Tiefdruckrinne nach Westen hin ab. Im Warmsektor ist weiterhin eine Konvergenz auszumachen. Durch die s\u00fcdliche bis s\u00fcdwestliche Str\u00f6mung wird sehr warme und feucht instabile Luft zu uns gef\u00fchrt. So kann sich bei uns heute eine kr\u00e4ftige Gewitterlage entwickeln. Vor allem an der Konvergenz kommt es schon um die Mittagszeit im Westen zu ersten Gewittern. Diese k\u00f6nnen bei ML-CAPE Werten von teilweise \u00fcber 1500 J\/kg und PPW Werten von \u00fcber 35 mm mit Starkregen, Hagel und Sturmb\u00f6en recht kr\u00e4ftig ausfallen. Vor allem k\u00f6nnen sich auch linienhafte Strukturen entwickeln und von daher k\u00f6nnen die Gewitter lokal auch Unwettercharakter mit heftigem Starkregen und gro\u00dfk\u00f6rnigem Hagel entwickeln. Davon betroffen ist insbesondere West- und Norddeutschland mit Schwerpunkten von NRW bis an die Unterelbe. Da die Modelle keinen eindeutigen Schwerpunkt der Entwicklung bestimmen Wenn am Abend die Kaltfront Deutschland erreicht, lassen die Schauer und Gewitter dann auch rasch nach. Grund ist die kr\u00e4ftige KLA auf der R\u00fcckseite der Kaltfront und der damit verbundene Druckanstieg. Nach Osten und S\u00fcden zu passiert dagegen zun\u00e4chst noch nichts. Hier scheint meist ungest\u00f6rt die Sonne und die Temperaturen k\u00f6nnen lokal \u00fcber 30 Grad erreichen, allerdings ist es recht schw\u00fcl.<\/p>\n<p>In der kommenden Nacht kommt die Front im Norden recht rasch nach Osten voran, w\u00e4hrend sie nach S\u00fcden zu zur\u00fcckh\u00e4ngt. Vor der Kaltfront ist weiterhin eine Konvergenz erkennbar, an der sich weitere Schauer und Gewitter bilden k\u00f6nnen. Daher sind zumindest in der ersten Nachth\u00e4lfte weitere unwetterartige Entwicklungen nicht ausgeschlossen. Die Schauer und Gewitterlinie erfassen am Morgen noch den \u00e4u\u00dfersten Osten und den S\u00fcdosten. Hinter der Kaltfront sorgt, wie schon erw\u00e4hnt, die KLA f\u00fcr Druckanstieg und es baut sich am Morgen \u00fcber Frankreich bis nach Westdeutschland reichend ein Bodenhoch auf. Daher klart es von Westen her auf und gebietsweise kann sich Nebel bilden.<\/p>\n<p>Mittwoch&#8230; stellt sich hinter dem Trog, der am Morgen noch den Osten \u00fcberquert, eine leicht m\u00e4andrierende westliche H\u00f6henstr\u00f6mung ein, in der sich schwach ausgepr\u00e4gte Tr\u00f6ge und Keile abwechseln. Ein erster dieser flachen R\u00fccken st\u00fctzt die Ausbildung eines abgeschlossenen Bodenhochs \u00fcber Deutschland, wobei sich der Schwerpunkt des Hochs gegen Abend ins \u00f6stliche Mitteleuropa verlagert.<\/p>\n<p>Diese Entwicklung sorgt am Mittwoch f\u00fcr einen meist ungest\u00f6rten Tag, wobei die Sonne im Westen am l\u00e4ngsten zu sehen ist. Aufgrund des Luftmassenwechsels ist etwas k\u00fchlere Luft zu uns geflossen, sodass die H\u00f6chsttemperaturen die 30-Grad-Marke nicht mehr erreichen. In weiten Teilen der Mitte und des S\u00fcdens wird aber ein Sommertag erreicht. Lediglich im S\u00fcden und da vor allem in Alpenn\u00e4he hat der Luftmassenwechsel noch nicht stattgefunden und die potentiell instabile Luft wurde noch nicht wegger\u00e4umt. Dort liegen au\u00dferdem die Reste des Frontensystems, das am Vortag das Gros des Landes \u00fcberquert hat. In der Folge k\u00f6nnen sich in Alpenn\u00e4he, bedingt durch orografische Triggerung, weitere Schauer und Gewitter entwickeln, die auch lokal wieder durch heftigen Starkregen die Unwetterschwelle \u00fcberschreiten k\u00f6nnen.<\/p>\n<p>In der Nacht zu Donnerstag verlagert sich das Bodentief weiter nach Osten und wir kommen auf der R\u00fcckseite des Hochs in eine s\u00fcdliche Bodenstr\u00f6mung und daher kommt die Luftmassengrenze an den Alpen wieder nordw\u00e4rts voran. Die Schauer und Gewitter im Bereich der instabilen Luft im \u00e4u\u00dfersten S\u00fcden brechen aber schon in der ersten Nachth\u00e4lfte zusammen. Weiterhin ger\u00e4t der Nordwesten zunehmend in den Einflussbereich eines hochreichenden Tiefs \u00fcber dem Ostatlantik, was sich aber vorerst nur durch starke Bew\u00f6lkung bemerkbar macht. Die Nacht bleibt meist ruhig und gebietsweise kann es bei Aufklaren Nebel bilden.<\/p>\n<p>Donnerstag&#8230; wandert auf der Vorderseite des ostatlantischen Troges ein Randtrog \u00fcber den Nordwesten hinweg nach Nordosten. Dadurch wird die Front \u00fcber der Mitte und dem S\u00fcden wieder aktiviert. Es kommt in der Mitte zu einer Wellbildung der Front und dadurch kommt auch die potentiell instabile Luft aus dem S\u00fcden weiter nordw\u00e4rts voran. Dadurch kann es anfangs in S\u00fcddeutschland, sp\u00e4ter auch im Osten wieder zu Schauern und Gewittern kommen, die meist im markanten Bereich liegen, lokal aber, bedingt durch recht hohe PPW Werte, hinsichtlich des Niederschlags auch die Unwetterschwelle \u00fcberschreiten. Die genaue Abfolge der Entwicklung ist aber noch recht unsicher.<\/p>\n<p>Der Norden wird dagegen im Tagesverlauf von dem frontalen Niederschlagsgebiet erfasst, wobei hierbei konvektive Umlagerungen keine Rolle spielen. Der Tag ist \u00fcberwiegend bedeckt, nur im S\u00fcdosten kann es auch l\u00e4ngere sonnige Abschnitte geben. Hier kann auch die 30-Grad-Marke geknackt werden. Sonst werden im Nordwesten bis 24 Grad, sonst 25 bis 29 Grad erreicht.<\/p>\n<p>Modellvergleich und -einsch\u00e4tzung<\/p>\n<p>Die Basisfelder der Modelle befinden sich in recht guter \u00dcbereinstimmung. Allerdings die Frage nach der Lage des Schwerpunkts der heutigen Entwicklung beantworten sie nicht einheitlich. Der differiert je nach Modell von Nordhessen und Westfalen bis nach Niedersachsen. Von daher und aufgrund der Annahme, dass die unwetterartigen Entwicklungen nur eher lokal auftreten, wurde auch von der Ausgabe einer Vorabinformation abgesehen.<\/p>\n<p>Vorhersage- und Beratungszentrale Offenbach Dipl. Met. Rolf Ullrich<\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Weiterf\u00fchrende Links<\/h3>\n<blockquote class=\"wp-embedded-content\" data-secret=\"3nWs9OOqiH\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/cape-faktor-und-lifted-index\/\">CAPE Faktor und Lifted Index<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;CAPE Faktor und Lifted Index&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/vorhersage\/cape-faktor-und-lifted-index\/embed\/#?secret=Oq48jLKisZ#?secret=3nWs9OOqiH\" data-secret=\"3nWs9OOqiH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"udNK1OQ1Oj\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/aktuelle-grafiken\/\">Aktuelle Grafiken<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Aktuelle Grafiken&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/aktuelle-grafiken\/embed\/#?secret=asJeKcup3P#?secret=udNK1OQ1Oj\" data-secret=\"udNK1OQ1Oj\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nZZB4IslwV\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/\">Wetterwarnungen<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wetterwarnungen&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetterwarnungen\/embed\/#?secret=SpKFUH738t#?secret=nZZB4IslwV\" data-secret=\"nZZB4IslwV\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"9DEiU9d37u\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/regenradar\/\">Regenradar<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Regenradar&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/regenradar\/embed\/#?secret=txc6EhhWDR#?secret=9DEiU9d37u\" data-secret=\"9DEiU9d37u\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"MOhgKXC8e5\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/blitzortung\/\">Blitzortung<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Blitzortung&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/blitzortung\/embed\/#?secret=hMkBLpP2il#?secret=MOhgKXC8e5\" data-secret=\"MOhgKXC8e5\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"pwvl188Jiu\"><p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/\">Wettercam<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Wettercam&#8220; &#8212; Wetterstation Brachwitz\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wetter\/wettercam\/embed\/#?secret=gmU3EaM9Qb#?secret=pwvl188Jiu\" data-secret=\"pwvl188Jiu\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gewitter mit Unwetterpotential 15.08.2017 Uhrzeit: 17:15 Schw\u00fcl und hei\u00df ist es. Das bedeutet jede Menge Energie f\u00fcr Gewitter. Heute Nachmittag hat ein kr\u00e4ftiger Downburst in Frankfurt am Main f\u00fcr ein Chaos gesorgt. Nun ist die Gewitterlinie auf dem Weg zu <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/gewitter-mit-unwetterpotential-15-08-2017\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":7663,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[4859,39,236,4875,4870,4869,4881,4885,4882,4868,4884,41,4860,4887,93,5,97,4848,5006,4883,4873,4872,44,4878,5005,487,4874,4877,4879,4876,63,452,462,95,4847,4871,4880,4886,5008,106,1006,231,5007,71,708,4,94,38,43,96,113],"yst_prominent_words":[2775,5717,3267,4709,4987,5716,1420,5511,2923,5720,2439,5718,5714,3846,4419,4462,5713,5719,5715,2502],"class_list":["post-7631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-beidersee","tag-brachwitz","tag-dauerregen","tag-deutleben","tag-dobis","tag-doeblitz","tag-domnitz","tag-dornitz","tag-doesel","tag-friedrichschwerz","tag-garsena","tag-gewitter","tag-gimritz","tag-gottgau","tag-hagel","tag-halle","tag-halle-saale","tag-haendel","tag-heide-nord","tag-kloschwitz","tag-lettewitz","tag-lettin","tag-loebejuen","tag-merbitz","tag-moederau","tag-morl","tag-muecheln","tag-nauendorf","tag-neuragozy","tag-neutz-lettewitz","tag-niederschlag","tag-orkanboeen","tag-rothenburg","tag-saalekreis","tag-sachen-anhalt","tag-salzmuende","tag-schiepzig","tag-schlettau","tag-sennewitz","tag-starkregen","tag-taupunkt","tag-temperatur","tag-trotha","tag-unwetter","tag-vorhersage","tag-wetter","tag-wetterbericht","tag-wettervorhersage","tag-wettin","tag-wettin-loebejuen","tag-wind"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2017\/08\/20785815_1458767364188915_2320571134451825359_o.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-1Z5","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/7631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=7631"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/7631\/revisions"}],"predecessor-version":[{"id":7664,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/7631\/revisions\/7664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/7663"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=7631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=7631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=7631"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=7631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}