{"id":8835,"date":"2018-02-20T15:16:56","date_gmt":"2018-02-20T13:16:56","guid":{"rendered":"http:\/\/www.hossi-im-netz.de\/wordpress\/?p=8835"},"modified":"2018-02-20T15:16:56","modified_gmt":"2018-02-20T13:16:56","slug":"moeglicher-rekordhagel-in-cordoba-argentinien","status":"publish","type":"post","link":"https:\/\/www.hossi-im-netz.de\/wordpress\/moeglicher-rekordhagel-in-cordoba-argentinien\/","title":{"rendered":"M\u00f6glicher Rekordhagel in Cordoba, Argentinien"},"content":{"rendered":"<h2 style=\"text-align: justify;\">M\u00f6glicher Rekordhagel in Cordoba, Argentinien<\/h2>\n<p style=\"text-align: justify;\">\nAnfang Februar brachten heftige Gewitter in den n\u00f6rdlichen und zentralen Bereichen Argentiniens Sturmb\u00f6en, Starkregen und gro\u00dfen Hagel. Besonders betroffen davon war Cordoba, wo extrem gro\u00dfer Hagel beobachtet wurde.<\/p>\n<p style=\"text-align: justify;\">In Argentinien, auf der S\u00fcdhalbkugel gelegen, herrscht von Dezember bis M\u00e4rz Sommer, wobei die gro\u00dfe Nord-S\u00fcd Ausdehnung Argentinien unterschiedlichste Klimazonen beschert. Unser Blick richtet sich dabei in diesem Thema des Tages auf die mit 1,3 Millionen Einwohnern nach Buenos Aires zweitgr\u00f6\u00dfte Stadt Argentiniens: Cordoba. Die Stadt wurde in der dem Text beigef\u00fcgten Abbildung jeweils mit einem gelben Stern hervorgehoben und liegt rund 650 km westnordwestlich der Hauptstadt Buenos Aires. Um die Entstehung der Gewitter nachvollziehen zu k\u00f6nnen, m\u00fcssen wir auch kurz auf die geografischen Besonderheiten in dieser Region eingehen. In a) ist ganz im Westen des Kontinents der gewaltige Nord-S\u00fcd ausgerichtete Gebirgszug der Anden auszumachen, der sich in H\u00f6henbereiche von 4000 bis teils mehr als 6000 m \u00fcber dem Meeresspiegel erstreckt. In b) wurde zudem ein relativ kleiner, \u00f6stlich der Anden gelegener Gebirgszug mit dem Namen &#8222;Sierras de Cordoba&#8220; hervorgehoben, entlang dem sich die Gewitter am 8. Februar unter anderem entwickeln sollten. Cordoba selber liegt nur rund 20 km \u00f6stlich dieses Gebirges, wobei das Gel\u00e4nde innerhalb dieser Distanz um mehr als 1000 m abf\u00e4llt.<\/p>\n<p style=\"text-align: justify;\">Die Stadt liegt im Einflussbereich der Westwindzone und wird daher immer wieder durch von West nach Ost ziehende Tiefdruckgebiete und Fronten beeinflusst. Das unglaublich vielf\u00e4ltige Klima in diesem Thema des Tages n\u00e4her zu beschreiben w\u00fcrde den Rahmen des Beitrages deutlich sprengen. Daher soll nur eine Auff\u00e4lligkeit hervorgehoben werden. Wenn die feuchte und k\u00fchle Luftmasse vom Pazifik kommend auf die Anden trifft, wird sie zum Aufsteigen gezwungen, k\u00fchlt sich ab und bildet Wolken- und Regentropfen. Im Lee der Anden hingegen beginnt die Luftmasse der rasch abfallenden Orografie folgend nach unten zu st\u00fcrzen und erw\u00e4rmt sich dabei um 1 Grad pro 100 Meter. Mal bricht diese Luftmasse als trockener und hei\u00dfer Fallwind bis zum Boden durch (namens &#8222;Zonda&#8220;), mal weht dieser hunderte von Metern \u00fcber dem Erdboden nach Osten.<\/p>\n<p style=\"text-align: justify;\">Am 8. Februar \u00fcberquerte den S\u00fcden von S\u00fcdamerika ein H\u00f6hentrog (siehe DWD Lexikon) von West nach Ost und sorgte daf\u00fcr, dass in rund 4 bis 5 km \u00fcber Grund ein m\u00e4\u00dfiger Westwind die Anden \u00fcberquerte (in a) durch die Windvektoren hervorgehoben, wobei ein kleiner Strich 5 Knoten (grob 9 km\/h) und jeder gro\u00dfe Strich jeweils 10 Knoten (grob 19 km\/h) Windgeschwindigkeit bedeuten). Diese trockene und warme Luftmasse str\u00f6mte \u00f6stlich der Anden und da speziell \u00f6stlich der &#8222;Sierras de Cordoba&#8220; \u00fcber eine bodennah sehr feuchte Luftmasse. Die am Boden gemessenen Taupunkte lagen zwischen 17 und 24 Grad, was in Verbindung mit H\u00f6chstwerten von 32 bis knapp 40 Grad eine extrem schw\u00fcle Luftmasse bedeutete (siehe b)).<\/p>\n<p style=\"text-align: justify;\">Tags\u00fcber sorgte die Sonneneinstrahlung nun daf\u00fcr, dass die feuchte und bodennah w\u00e4rmer werdende Luftmasse immer mehr danach strebte aufzusteigen, da Luft eine immer geringere Dichte besitzt und leichter wird, je w\u00e4rmer sie ist. Diese Aufw\u00e4rtsbewegung wurde allerdings bis weit in den Tag durch die dar\u00fcber liegende trockene und vor allem warme Luftmasse unterdr\u00fcckt, die von den Anden ostw\u00e4rts str\u00f6mte. Dieser Zustand wird als &#8222;potentiell labil&#8220; bezeichnet, wenn, wie hier, die Luftmasse am Aufsteigen (noch) gehindert wird. In a) ist diese Labilit\u00e4t farblich dargestellt, wobei rote Farben eine sehr labile Atmosph\u00e4re andeuten mit dem Potential f\u00fcr kr\u00e4ftige Gewitter. Im Verlauf des sp\u00e4ten Nachmittags allerdings wurde die bodennahe Luftmasse soweit aufgeheizt, dass sie \u00fcber der &#8222;Sierras de Cordoba&#8220; in die H\u00f6he schoss. Die aufsteigende Luft wird auch als &#8222;Aufwind&#8220; bezeichnet. Durch das rasche Aufsteigen k\u00fchlte sich die Luft schnell ab, bildete Wolken- und Regentr\u00f6pfchen und letztendlich gewaltige Gewitterwolken, die mit heftigem Regen einhergingen. Gewitterwolken beinhalten aber auch Hagelk\u00f6rner, die bei solch heftig aufsteigenden Luftmassen wie am 8. Februar sehr lange in den Wolken gehalten werden k\u00f6nnen und immer weiter anwachsen, bis sie nicht mehr in der Luft gehalten werden k\u00f6nnen. Dann fallen die Hagelk\u00f6rner mal kleiner, mal gr\u00f6\u00dfer zur Erde.<\/p>\n<p style=\"text-align: justify;\">In c) ist im Satellitenbild knapp westlich von Cordoba ein roter Punkt zu sehen. Je oranger und roter die Farbe, desto k\u00e4lter und hochreichender ist die Wolke. Dies ist ein sogenannter &#8222;overshooting top&#8220;, wo die Gewitterwolke bis in die untere Stratosph\u00e4re reicht. Dort sind die st\u00e4rksten Aufwinde zu finden, die Cordoba zu dem Zeitpunkt \u00fcberqueren. Dieses Gewitter lie\u00df dort f\u00fcr 20 Minuten Hagel&#8220;k\u00f6rner&#8220; mit teils mehr als 10 cm Durchmesser niederprasseln. Eines der Hagelgeschosse wies sogar einen Durchmesser von knapp 18 cm auf, was, wenn best\u00e4tigt, ein neuer Gr\u00f6\u00dfenrekord f\u00fcr die s\u00fcdliche Hemisph\u00e4re darstellen w\u00fcrde. In d) erkennt man, wie dieses Unwetter ohne Abschw\u00e4chung weiter nach Nordosten zog und wie sich auch weiter s\u00fcdlich ein weiteres heftiges Gewitter bildete, das ebenfalls gro\u00dfen Hagel brachte. Sehr sch\u00f6n sind auch Schwerewellen am Oberrand des Gewitters auszumachen, die entstehen, wenn der Aufwind stark vereinfacht gesprochen in die w\u00e4rmere und somit stabil geschichtete Tropopause vorst\u00f6\u00dft, somit bildlich gesprochen wie gegen eine Wand l\u00e4uft und wieder in sich zusammenf\u00e4llt. Dabei bildet sich ein overshooting top, der in sich zusammenf\u00e4llt und \u00fcbrig bleiben nur Cirren (siehe DWD Lexikon). Diese werden in der Meteorologie als &#8222;jumping cirrus&#8220; bezeichnet, sind ebenfalls in Indikator f\u00fcr heftige Gewitter und wurden in d) hervorgehoben. Wie in e) zu sehen ist dauerten die heftigen Unwetter bis weit in die Nacht an und brachten neben gro\u00dfem Hagel auch Starkregen, Sturmb\u00f6en und unz\u00e4hlige Blitzentladungen.<\/p>\n<p style=\"text-align: justify;\">Auch wenn Cordoba in der argentinischen Hagelzone liegt, wo immer wieder gro\u00dfe Hagelereignisse vermeldet werden, wird den Bewohnern dieses Ereignis dank der gewaltigen Hageldurchmesser noch lange in Erinnerung bleiben. Nun aber neigt sich die Sommerzeit allm\u00e4hlich dem Ende entgegen und aus klimatologischer Sicht verringert sich nun sowohl die Anzahl, als auch die Intensit\u00e4t der Gewittertage und -ereignisse.<\/p>\n<p style=\"text-align: justify;\">Dipl.-Met. Helge Tuschy<\/p>\n<p style=\"text-align: justify;\">Deutscher Wetterdienst Vorhersage- und Beratungszentrale Offenbach, den 20.02.2018<\/p>\n<p style=\"text-align: justify;\">Copyright (c) Deutscher Wetterdienst<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8836\" data-permalink=\"https:\/\/www.hossi-im-netz.de\/wordpress\/moeglicher-rekordhagel-in-cordoba-argentinien\/7a025185-675e-45c8-9b11-a7c93beaa969\/\" data-orig-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969.jpeg\" data-orig-size=\"1293,995\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"M\u00f6glicher Rekordhagel in Cordoba, Argentinien\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969-1024x788.jpeg\" class=\"alignnone size-full wp-image-8836\" src=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969.jpeg\" alt=\"M\u00f6glicher Rekordhagel in Cordoba, Argentinien\" width=\"1293\" height=\"995\" srcset=\"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969.jpeg 1293w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969-300x231.jpeg 300w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969-768x591.jpeg 768w, https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969-1024x788.jpeg 1024w\" sizes=\"auto, (max-width: 1293px) 100vw, 1293px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6glicher Rekordhagel in Cordoba, Argentinien Anfang Februar brachten heftige Gewitter in den n\u00f6rdlichen und zentralen Bereichen Argentiniens Sturmb\u00f6en, Starkregen und gro\u00dfen Hagel. Besonders betroffen davon war Cordoba, wo extrem gro\u00dfer Hagel beobachtet wurde. In Argentinien, auf der S\u00fcdhalbkugel gelegen, herrscht <span class=\"excerpt-dots\">&hellip;<\/span> <a class=\"more-link\" href=\"https:\/\/www.hossi-im-netz.de\/wordpress\/moeglicher-rekordhagel-in-cordoba-argentinien\/\"><span class=\"more-msg\">Weiterlesen &rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":8836,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[37],"tags":[8765,8764,93,8763,71],"yst_prominent_words":[8760,6128,8754,8753,1216,8756,3031,3267,8761,4517,8762,8757,3516,8759,8755,8751,8752,8750,8758,3707],"class_list":["post-8835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wetterblog","tag-argentinien","tag-cordoba","tag-hagel","tag-rekordhagel","tag-unwetter"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-content\/uploads\/2018\/02\/7A025185-675E-45C8-9B11-A7C93BEAA969.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5DnIb-2iv","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/8835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=8835"}],"version-history":[{"count":1,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/8835\/revisions"}],"predecessor-version":[{"id":8837,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/posts\/8835\/revisions\/8837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media\/8836"}],"wp:attachment":[{"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=8835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=8835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=8835"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.hossi-im-netz.de\/wordpress\/wp-json\/wp\/v2\/yst_prominent_words?post=8835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}